{"id":92606,"date":"2021-12-25T16:01:28","date_gmt":"2021-12-25T21:01:28","guid":{"rendered":"https:\/\/fraynelson.com\/blog\/?p=92606"},"modified":"2021-12-22T19:43:44","modified_gmt":"2021-12-23T00:43:44","slug":"rosario-de-las-semanas-2021-12-26","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2021\/12\/25\/rosario-de-las-semanas-2021-12-26\/","title":{"rendered":"ROSARIO de las Semanas 2021\/12\/26"},"content":{"rendered":"<p><div class=\"powerpress_player\" id=\"powerpress_player_6440\"><audio class=\"wp-audio-shortcode\" id=\"audio-92606-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa07.mp3?_=1\" \/><a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa07.mp3\">http:\/\/traffic.libsyn.com\/fraynelson\/rosa07.mp3<\/a><\/audio><\/div><p class=\"powerpress_links powerpress_links_mp3\" style=\"margin-bottom: 1px !important;\">Podcast: <a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa07.mp3\" class=\"powerpress_link_pinw\" target=\"_blank\" title=\"Play in new window\" onclick=\"return powerpress_pinw('https:\/\/fraynelson.com\/blog\/?powerpress_pinw=92606-podcast');\" rel=\"nofollow\">Play in new window<\/a> | <a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa07.mp3\" class=\"powerpress_link_d\" title=\"Download\" rel=\"nofollow\" download=\"rosa07.mp3\">Download<\/a><\/p><p class=\"powerpress_links powerpress_subscribe_links\">Subscribe: <a href=\"https:\/\/fraynelson.com\/blog\/feed\/podcast\/\" class=\"powerpress_link_subscribe powerpress_link_subscribe_rss\" target=\"_blank\" title=\"Subscribe via RSS\" rel=\"nofollow\">RSS<\/a><\/p>#RosarioFrayNelson para el <strong>Domingo<\/strong>:<br \/>\nContemplamos los <em>Misterios de la Gloria del Se\u00f1or<\/em><br \/>\n<iframe loading=\"lazy\" title=\"Rosario de las Semanas - Para los d\u00edas DOMINGOS\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/ez8VQMk9RDY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><br \/>\nUsamos <a href=\"http:\/\/fraynelson.com\/oraciones.html\" target=\"_blank\" rel=\"noopener noreferrer\">esta versi\u00f3n de las oraciones<\/a>.<\/p>\n<ol>\n<li>En el primer misterio glorioso contemplamos <em>la Resurrecci\u00f3n de Nuestro Se\u00f1or Jesucristo<\/em>.<\/li>\n<li>En el segundo misterio glorioso contemplamos <em>la Ascensi\u00f3n de Cristo a los Cielos<\/em>.<\/li>\n<li>En el tercer misterio glorioso contemplamos <em>el d\u00eda de Pentecost\u00e9s: la efusi\u00f3n del Esp\u00edritu Santo da nacimiento a la Iglesia<\/em>.<\/li>\n<li>En el cuarto misterio glorioso contemplamos <em>la santidad de la Iglesia, especialmente visible en sus m\u00e1rtires, ya desde los primeros tiempos<\/em>.<\/li>\n<li>En el quinto misterio glorioso contemplamos <em>la Asunci\u00f3n de la Virgen Mar\u00eda y el poder singular de su intercesi\u00f3n por la Iglesia que peregrina<\/em>.<\/li>\n<li>En el sexto misterio glorioso contemplamos <em>la segunda venida de Cristo, y que de su Reinado han de participar para siempre la Virgen Mar\u00eda y todos los santos<\/em>.<\/li>\n<li>En el s\u00e9ptimo misterio glorioso contemplamos que <em>la muerte misma morir\u00e1, y que Dios ser\u00e1 todo en todos<\/em>.<\/li>\n<\/ol>\n<p>[<strong>REPRODUCCI\u00d3N PERMITIDA<\/strong> \u2013 Este es un ejercicio privado de devoci\u00f3n &#8220;<em>ad experimentum<\/em>&#8221; en proceso de aprobaci\u00f3n oficial. Puede divulgarse en las redes sociales, blogs, emisoras de radio, y otros medios siempre que al mismo tiempo se haga la presente advertencia.]<\/p>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1140,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,1265],"tags":[],"class_list":["post-92606","post","type-post","status-publish","format-standard","hentry","category-audio","category-rosario-de-las-semanas"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/92606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1140"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=92606"}],"version-history":[{"count":1,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/92606\/revisions"}],"predecessor-version":[{"id":92607,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/92606\/revisions\/92607"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=92606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=92606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=92606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}