{"id":87011,"date":"2021-03-27T15:24:12","date_gmt":"2021-03-27T20:24:12","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=87011"},"modified":"2021-03-27T15:24:12","modified_gmt":"2021-03-27T20:24:12","slug":"zenit-y-catholic-net-unen-fuerzas","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2021\/03\/27\/zenit-y-catholic-net-unen-fuerzas\/","title":{"rendered":"Zenit y Catholic.Net unen fuerzas"},"content":{"rendered":"<p>La agencia cat\u00f3lica internacional <a href=\"http:\/\/zenit.org\" rel=\"noopener\" target=\"_blank\">Zenit<\/a> se une a <a href=\"http:\/\/es.catholic.net\" rel=\"noopener\" target=\"_blank\">Catholic.Net<\/a>, el primer portal cat\u00f3lico de habla hispana.<\/p>\n<p><a href=\"https:\/\/www.evernote.com\/shard\/s254\/sh\/eefe183e-e840-47a1-9f55-aef6d8dd796c\/ce1a4405a53edb457d8adb34c2411982\" rel=\"noopener\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/fraynelson.com\/banco_imagenes\/recomendados\/20210329.jpg\" alt=\"\" \/><\/p>\n<p>Haz clic aqu\u00ed!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La agencia cat\u00f3lica internacional Zenit se une a Catholic.Net, el primer portal cat\u00f3lico de habla hispana. Haz clic aqu\u00ed!<\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[620,56],"tags":[],"class_list":["post-87011","post","type-post","status-publish","format-standard","hentry","category-enlaces","category-la-iglesia-hoy"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/87011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=87011"}],"version-history":[{"count":1,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/87011\/revisions"}],"predecessor-version":[{"id":87012,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/87011\/revisions\/87012"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=87011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=87011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=87011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}