{"id":85743,"date":"2021-01-25T16:01:48","date_gmt":"2021-01-25T21:01:48","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=85743"},"modified":"2021-01-24T14:37:43","modified_gmt":"2021-01-24T19:37:43","slug":"rosario-de-las-semanas-20210126","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2021\/01\/25\/rosario-de-las-semanas-20210126\/","title":{"rendered":"ROSARIO de las Semanas 20210126"},"content":{"rendered":"<p>#RosarioFrayNelson para el <strong>Martes<\/strong>:<br \/>\nContemplamos los <em>Misterios de la Antigua Alianza<\/em><br \/>\n<iframe loading=\"lazy\" title=\"Rosario de las Semanas - Para los d\u00edas MARTES\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/TsCVbPXq4QY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><br \/>\n<audio class=\"wp-audio-shortcode\" id=\"audio-85743-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa02.mp3?_=1\" \/><a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa02.mp3\">http:\/\/traffic.libsyn.com\/fraynelson\/rosa02.mp3<\/a><\/audio><br \/>\nUsamos <a href=\"http:\/\/fraynelson.com\/oraciones.html\" target=\"_blank\" rel=\"noopener noreferrer\">esta versi\u00f3n de las oraciones<\/a>.<\/p>\n<ol>\n<li>En el primer misterio de la Antigua Alianza contemplamos <em>la paciencia de Dios, que no detuvo su amor ante el pecado de los hombres<\/em>.<\/li>\n<li>En el segundo misterio de la Antigua Alianza contemplamos <em>el camino de fe de Abraham<\/em>.<\/li>\n<li>En el tercer misterio de la Antigua Alianza contemplamos <em>el \u00e9xodo de la tierra de Egipto<\/em>.<\/li>\n<li>En el cuarto misterio de la Antigua Alianza contemplamos <em>el don de la Ley hecho a Mois\u00e9s y a su pueblo junto al Monte Sina\u00ed<\/em>.<\/li>\n<li>En el quinto misterio de la Antigua Alianza contemplamos <em>la gran promesa de Dios al rey David: que el cetro real no se apartar\u00eda de su descendencia<\/em>.<\/li>\n<li>En el sexto misterio de la Antigua Alianza contemplamos <em>la valiente vocaci\u00f3n de los profetas, por quienes el Esp\u00edritu Santo nos habl\u00f3 de muchas maneras<\/em>.<\/li>\n<li>En el s\u00e9ptimo misterio de la Antigua Alianza contemplamos a <em>el peque\u00f1o resto de Israel, que permaneci\u00f3 fiel y fue semilla de la Nueva y Eterna Alianza<\/em>.<\/li>\n<\/ol>\n<p>[<strong>REPRODUCCI\u00d3N PERMITIDA<\/strong> \u2013 Este es un ejercicio privado de devoci\u00f3n &#8220;<em>ad experimentum<\/em>&#8221; en proceso de aprobaci\u00f3n oficial. Puede divulgarse en las redes sociales, blogs, emisoras de radio, y otros medios siempre que al mismo tiempo se haga la presente advertencia.]<\/p>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1140,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,1265],"tags":[],"class_list":["post-85743","post","type-post","status-publish","format-standard","hentry","category-audio","category-rosario-de-las-semanas"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/85743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1140"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=85743"}],"version-history":[{"count":1,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/85743\/revisions"}],"predecessor-version":[{"id":85747,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/85743\/revisions\/85747"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=85743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=85743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=85743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}