{"id":8471,"date":"2011-01-21T10:18:10","date_gmt":"2011-01-21T15:18:10","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=8471"},"modified":"2011-01-21T10:18:10","modified_gmt":"2011-01-21T15:18:10","slug":"de-como-sana-cristo-las-divisiones-entre-personas","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2011\/01\/21\/de-como-sana-cristo-las-divisiones-entre-personas\/","title":{"rendered":"De como sana Cristo las divisiones entre personas"},"content":{"rendered":"<p>Cristo es manantial de bondad que as\u00ed atrae a todos a que reconozcan sus propias dolencias y necesidades. Las divisiones entre personas y pueblos caen entonces.<\/p>\n<p>[podcast]http:\/\/fraynelson.com\/homilias_mp3\/i024006a.mp3[\/podcast]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cristo es manantial de bondad que as\u00ed atrae a todos a que reconozcan sus propias dolencias y necesidades. Las divisiones entre personas y pueblos caen entonces. [podcast]http:\/\/fraynelson.com\/homilias_mp3\/i024006a.mp3[\/podcast]<\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,307,356,430],"tags":[],"class_list":["post-8471","post","type-post","status-publish","format-standard","hentry","category-audio","category-homilias","category-sanacion","category-unidad"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/8471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=8471"}],"version-history":[{"count":1,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/8471\/revisions"}],"predecessor-version":[{"id":8472,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/8471\/revisions\/8472"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=8471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=8471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=8471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}