{"id":81686,"date":"2020-08-04T16:01:05","date_gmt":"2020-08-04T21:01:05","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=81686"},"modified":"2020-07-27T14:30:14","modified_gmt":"2020-07-27T19:30:14","slug":"rosario-de-las-semanas-20200805","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2020\/08\/04\/rosario-de-las-semanas-20200805\/","title":{"rendered":"ROSARIO de las Semanas 20200805"},"content":{"rendered":"<p>#RosarioFrayNelson para el <strong>Mi\u00e9rcoles<\/strong>:<br \/>\nContemplamos los <em>Misterios de la Infancia de Jes\u00fas<\/em><br \/>\n<iframe loading=\"lazy\" title=\"Rosario de las Semanas - Para los d\u00edas MI\u00c9RCOLES\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/iNaUDy36-0w?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><br \/>\n<audio class=\"wp-audio-shortcode\" id=\"audio-81686-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa03.mp3?_=1\" \/><a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa03.mp3\">http:\/\/traffic.libsyn.com\/fraynelson\/rosa03.mp3<\/a><\/audio><br \/>\nUsamos <a href=\"http:\/\/fraynelson.com\/oraciones.html\" target=\"_blank\" rel=\"noopener noreferrer\">esta versi\u00f3n de las oraciones<\/a>.<\/p>\n<ol>\n<li>En el primer misterio de la infancia contemplamos <em>la Anunciaci\u00f3n a Mar\u00eda Sant\u00edsima y la Encarnaci\u00f3n del Hijo de Dios<\/em>.<\/li>\n<li>En el segundo misterio de la infancia contemplamos <em>la visita de la Virgen Madre a su pariente Isabel<\/em>.<\/li>\n<li>En el tercer misterio de la infancia contemplamos <em>el sufrimiento que pas\u00f3 San Jos\u00e9, y la fe amorosa que tuvo<\/em>.<\/li>\n<li>En el cuarto misterio de la infancia contemplamos <em>el Nacimiento del Hijo de Dios en el humilde portal de Bel\u00e9n<\/em>.<\/li>\n<li>En el quinto misterio de la infancia contemplamos <em>la Epifan\u00eda: Jes\u00fas es luz para las naciones, y as\u00ed es adorado por unos magos venidos de Oriente<\/em>.<\/li>\n<li>En el sexto misterio de la infancia contemplamos <em>la Presentaci\u00f3n del Ni\u00f1o Jes\u00fas en el templo de Jerusal\u00e9n<\/em>.<\/li>\n<li>En el s\u00e9ptimo misterio de la infancia contemplamos a <em>Jes\u00fas Ni\u00f1o en el templo, ocupado de las cosas de su Padre del Cielo<\/em>.<\/li>\n<\/ol>\n<p>[<strong>REPRODUCCI\u00d3N PERMITIDA<\/strong> \u2013 Este es un ejercicio privado de devoci\u00f3n &#8220;<em>ad experimentum<\/em>&#8221; en proceso de aprobaci\u00f3n oficial. Puede divulgarse en las redes sociales, blogs, emisoras de radio, y otros medios siempre que al mismo tiempo se haga la presente advertencia.]<\/p>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1140,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,1265],"tags":[],"class_list":["post-81686","post","type-post","status-publish","format-standard","hentry","category-audio","category-rosario-de-las-semanas"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/81686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1140"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=81686"}],"version-history":[{"count":1,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/81686\/revisions"}],"predecessor-version":[{"id":81693,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/81686\/revisions\/81693"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=81686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=81686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=81686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}