{"id":80435,"date":"2020-06-07T16:01:00","date_gmt":"2020-06-07T21:01:00","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=80435"},"modified":"2020-06-03T15:37:35","modified_gmt":"2020-06-03T20:37:35","slug":"rosario-de-las-semanas-20200608","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2020\/06\/07\/rosario-de-las-semanas-20200608\/","title":{"rendered":"ROSARIO de las Semanas 20200608"},"content":{"rendered":"<p>#RosarioFrayNelson para el <strong>Lunes<\/strong>:<br \/>\nContemplamos los <em>Misterios de la Creaci\u00f3n<\/em><br \/>\n<iframe loading=\"lazy\" title=\"Rosario de las Semanas - Para los d\u00edas LUNES\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/mM-pdA4az_g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><br \/>\n<audio class=\"wp-audio-shortcode\" id=\"audio-80435-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa01.mp3?_=1\" \/><a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa01.mp3\">http:\/\/traffic.libsyn.com\/fraynelson\/rosa01.mp3<\/a><\/audio><br \/>\nUsamos <a href=\"http:\/\/fraynelson.com\/oraciones.html\" target=\"_blank\" rel=\"noopener noreferrer\">esta versi\u00f3n de las oraciones<\/a>.<\/p>\n<ol>\n<li>En el primer misterio de la creaci\u00f3n contemplamos <em>la sabidur\u00eda y la hermosura con que Dios ha dispuesto todas las cosas, en su tiempo y en su lugar<\/em>.<\/li>\n<li>En el segundo misterio de la creaci\u00f3n contemplamos <em>el poder de la Palabra creadora de Dios, pues todo ha venido a ser porque \u00e9l lo dijo y existi\u00f3<\/em>.<\/li>\n<li>En el tercer misterio de la creaci\u00f3n contemplamos que <em>Dios hizo los cielos y los Santos Ej\u00e9rcitos celestiales<\/em>.<\/li>\n<li>En el cuarto misterio de la creaci\u00f3n contemplamos que <em>Dios hizo el universo visible, y suyo es cuanto hay en esta tierra<\/em>.<\/li>\n<li>En el quinto misterio de la creaci\u00f3n contemplamos que <em>Dios form\u00f3 al hombre y a la mujer<\/em>.<\/li>\n<li>En el sexto misterio de la creaci\u00f3n contemplamos <em>la vocaci\u00f3n del hombre para que se multiplique y domine la tierra en nombre de Dios y obediencia a \u00e9l<\/em>.<\/li>\n<li>En el s\u00e9ptimo misterio de la creaci\u00f3n contemplamos <em>el para\u00edso, primera imagen de la felicidad que Dios quiso para sus hijos.<\/em><\/li>\n<\/ol>\n<p>[<strong>REPRODUCCI\u00d3N PERMITIDA<\/strong> \u2013 Este es un ejercicio privado de devoci\u00f3n &#8220;<em>ad experimentum<\/em>&#8221; en proceso de aprobaci\u00f3n oficial. Puede divulgarse en las redes sociales, blogs, emisoras de radio, y otros medios siempre que al mismo tiempo se haga la presente advertencia.]<\/p>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1140,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,1265],"tags":[],"class_list":["post-80435","post","type-post","status-publish","format-standard","hentry","category-audio","category-rosario-de-las-semanas"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/80435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1140"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=80435"}],"version-history":[{"count":1,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/80435\/revisions"}],"predecessor-version":[{"id":80445,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/80435\/revisions\/80445"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=80435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=80435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=80435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}