{"id":80429,"date":"2020-06-12T16:01:33","date_gmt":"2020-06-12T21:01:33","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=80429"},"modified":"2020-06-03T15:29:16","modified_gmt":"2020-06-03T20:29:16","slug":"rosario-de-las-semanas-20200613","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2020\/06\/12\/rosario-de-las-semanas-20200613\/","title":{"rendered":"ROSARIO de las Semanas 20200613"},"content":{"rendered":"<p><div class=\"powerpress_player\" id=\"powerpress_player_4835\"><audio class=\"wp-audio-shortcode\" id=\"audio-80429-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa06.mp3?_=1\" \/><a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa06.mp3\">http:\/\/traffic.libsyn.com\/fraynelson\/rosa06.mp3<\/a><\/audio><\/div><p class=\"powerpress_links powerpress_links_mp3\" style=\"margin-bottom: 1px !important;\">Podcast: <a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa06.mp3\" class=\"powerpress_link_pinw\" target=\"_blank\" title=\"Play in new window\" onclick=\"return powerpress_pinw('https:\/\/fraynelson.com\/blog\/?powerpress_pinw=80429-podcast');\" rel=\"nofollow\">Play in new window<\/a> | <a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa06.mp3\" class=\"powerpress_link_d\" title=\"Download\" rel=\"nofollow\" download=\"rosa06.mp3\">Download<\/a><\/p><p class=\"powerpress_links powerpress_subscribe_links\">Subscribe: <a href=\"https:\/\/fraynelson.com\/blog\/feed\/podcast\/\" class=\"powerpress_link_subscribe powerpress_link_subscribe_rss\" target=\"_blank\" title=\"Subscribe via RSS\" rel=\"nofollow\">RSS<\/a><\/p>#RosarioFrayNelson para el <strong>S\u00e1bado<\/strong>:<br \/>\nContemplamos los <em>Misterios del Silencio de Dios<\/em><br \/>\n<iframe loading=\"lazy\" title=\"Rosario de las Semanas - Para los d\u00edas S\u00c1BADOS\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/u0jSQ_FeZRg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><br \/>\nUsamos <a href=\"http:\/\/fraynelson.com\/oraciones.html\" target=\"_blank\" rel=\"noopener noreferrer\">esta versi\u00f3n de las oraciones<\/a>.<\/p>\n<ol>\n<li>En el primer misterio del silencio contemplamos que <em>del costado de Cristo en la Cruz brotaron sangre y agua<\/em>.<\/li>\n<li>En el segundo misterio del silencio contemplamos <em>el valor de aquellos que no eran ap\u00f3stoles y s\u00ed permanecieron junto a la Cruz y cuidaron del cuerpo de Cristo muerto<\/em>.<\/li>\n<li>En el tercer misterio del silencio contemplamos a <em>Jesucristo, puesto en un sepulcro nuevo<\/em>.<\/li>\n<li>En el cuarto misterio del silencio contemplamos a <em>Jes\u00fas, que baja hasta el fondo del reino de la muerte, para que los justos que de antiguo esperaron en \u00e9l encuentren a su Redentor<\/em>.<\/li>\n<li>En el quinto misterio del silencio contemplamos <em>el anonadamiento de Cristo, que siendo Hijo aprendi\u00f3 sufriendo a obedecer<\/em>.<\/li>\n<li>En el sexto misterio del silencio contemplamos <em>la soledad llena de fe de la Sant\u00edsima Virgen Mar\u00eda<\/em>.<\/li>\n<li>En el s\u00e9ptimo misterio del silencio contemplamos <em>la inmensa compasi\u00f3n de Dios Padre, que tanto am\u00f3 al mundo que le dio a su \u00fanico Hijo para que todo el que cree en \u00e9l no perezca<\/em>.<\/li>\n<\/ol>\n<p>[<strong>REPRODUCCI\u00d3N PERMITIDA<\/strong> \u2013 Este es un ejercicio privado de devoci\u00f3n &#8220;<em>ad experimentum<\/em>&#8221; en proceso de aprobaci\u00f3n oficial. Puede divulgarse en las redes sociales, blogs, emisoras de radio, y otros medios siempre que al mismo tiempo se haga la presente advertencia.]<\/p>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1140,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,1265],"tags":[],"class_list":["post-80429","post","type-post","status-publish","format-standard","hentry","category-audio","category-rosario-de-las-semanas"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/80429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1140"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=80429"}],"version-history":[{"count":1,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/80429\/revisions"}],"predecessor-version":[{"id":80442,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/80429\/revisions\/80442"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=80429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=80429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=80429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}