{"id":80358,"date":"2020-05-31T18:58:34","date_gmt":"2020-05-31T23:58:34","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=80358"},"modified":"2020-05-31T18:58:34","modified_gmt":"2020-05-31T23:58:34","slug":"hijos-de-dios","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2020\/05\/31\/hijos-de-dios\/","title":{"rendered":"\u00a1Hijos de Dios!"},"content":{"rendered":"<p>Al traerte a la Iglesia, el Se\u00f1or ha puesto en tu alma un sello indeleble, por medio del Bautismo: eres hijo de Dios. -No lo olvides.<\/p>\n<p>Dale muchas gracias a Jes\u00fas, porque por El, con El y en El, t\u00fa te puedes llamar hijo de Dios.<\/p>\n<p>Si nos sentimos hijos predilectos de nuestro Padre de los Cielos, \u00a1que eso somos!, \u00bfc\u00f3mo no vamos a estar alegres siempre? -Pi\u00e9nsalo.<\/p>\n<p><a href=\"https:\/\/fraynelson.com\/blog\/categorias\/personas\/san-josemaria-escriva\/\">M\u00e1s pensamientos de San Josemar\u00eda<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al traerte a la Iglesia, el Se\u00f1or ha puesto en tu alma un sello indeleble, por medio del Bautismo: eres hijo de Dios. -No lo olvides. Dale muchas gracias a Jes\u00fas, porque por El, con El y en El, t\u00fa te puedes llamar hijo de Dios. Si nos sentimos hijos predilectos de nuestro Padre de &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fraynelson.com\/blog\/2020\/05\/31\/hijos-de-dios\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;\u00a1Hijos de Dios!&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[953,454],"tags":[],"class_list":["post-80358","post","type-post","status-publish","format-standard","hentry","category-camino-surco-forja","category-hijos"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/80358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=80358"}],"version-history":[{"count":1,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/80358\/revisions"}],"predecessor-version":[{"id":80359,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/80358\/revisions\/80359"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=80358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=80358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=80358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}