{"id":78379,"date":"2020-03-11T11:12:38","date_gmt":"2020-03-11T16:12:38","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=78379"},"modified":"2020-03-09T15:20:18","modified_gmt":"2020-03-09T20:20:18","slug":"respuesta-a-algunos-argumentos-contra-el-libre-albedrio","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2020\/03\/11\/respuesta-a-algunos-argumentos-contra-el-libre-albedrio\/","title":{"rendered":"Respuesta a algunos argumentos contra el libre albedr\u00edo"},"content":{"rendered":"<p>&#8220;Jonathan Edwards (1703 \u2013 1758) es uno de los m\u00e1ximos referentes teol\u00f3gicos del calvinismo norteamericano. Su obra tal vez m\u00e1s famosa es \u201cUna investigaci\u00f3n acerca de las nociones modernas prevalentes sobre la libertad de la voluntad, que se supone que es esencial a la agencia moral, la virtud y el vicio, las recompensas y el castigo, el elogio y la inculpaci\u00f3n\u201d, de 1754. En la obra Edwards polemiza con el \u201carminianismo\u201d, que es una escisi\u00f3n del calvinismo basada justamente en que Jacobo Arminio, te\u00f3logo calvinista holand\u00e9s, defend\u00eda el libre albedr\u00edo contra Calvino y sus seguidores. Nuestra intenci\u00f3n es analizar aqu\u00ed los argumentos de Edwards contra lo que entendemos que es la concepci\u00f3n com\u00fan y universal de \u201clibre albedr\u00edo\u201d&#8230;&#8221;<\/p>\n<p><a href=\"https:\/\/www.evernote.com\/shard\/s254\/sh\/9852ada1-cb76-4fbc-8cf2-4b1e920a2615\/f535564f3d2cc899a9087a14b8f74ca7\" rel=\"noopener noreferrer\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/fraynelson.com\/banco_imagenes\/recomendados\/20200313.jpg\" alt=\"\" \/><\/p>\n<p>Haz clic aqu\u00ed!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Jonathan Edwards (1703 \u2013 1758) es uno de los m\u00e1ximos referentes teol\u00f3gicos del calvinismo norteamericano. Su obra tal vez m\u00e1s famosa es \u201cUna investigaci\u00f3n acerca de las nociones modernas prevalentes sobre la libertad de la voluntad, que se supone que es esencial a la agencia moral, la virtud y el vicio, las recompensas y el &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fraynelson.com\/blog\/2020\/03\/11\/respuesta-a-algunos-argumentos-contra-el-libre-albedrio\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;Respuesta a algunos argumentos contra el libre albedr\u00edo&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[620,412,781],"tags":[],"class_list":["post-78379","post","type-post","status-publish","format-standard","hentry","category-enlaces","category-libertad","category-voluntad"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/78379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=78379"}],"version-history":[{"count":1,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/78379\/revisions"}],"predecessor-version":[{"id":78380,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/78379\/revisions\/78380"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=78379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=78379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=78379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}