{"id":7753,"date":"2010-11-09T01:17:25","date_gmt":"2010-11-09T06:17:25","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=7753"},"modified":"2010-11-08T18:20:24","modified_gmt":"2010-11-08T23:20:24","slug":"sobre-el-opus-angelorum","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2010\/11\/09\/sobre-el-opus-angelorum\/","title":{"rendered":"Sobre el Opus Angelorum"},"content":{"rendered":"<p><img decoding=\"async\" src=\"http:\/\/fraynelson.com\/banco_imagenes\/recomendados\/20101111.jpg\" alt=\"opus angelorum\" \/><br \/>\n&#8220;Tal como se presenta hoy, el \u201cOpus Angelorum\u201d es, por lo tanto, una asociaci\u00f3n p\u00fablica de la Iglesia en armon\u00eda con la doctrina tradicional y las normas de la suprema autoridad de la Iglesia. Ella difunde entre los fieles la devoci\u00f3n a los santos \u00e1ngeles, exhorta a rezar por los sacerdotes y promueve el amor por la Pasi\u00f3n de Cristo y su uni\u00f3n a ella. No existe por tanto ning\u00fan obst\u00e1culo de orden doctrinal o disciplinar que impida a los ordinarios locales acoger en sus di\u00f3cesis tal asociaci\u00f3n y favorecer su crecimiento. Sin embargo, esta Congregaci\u00f3n quiere llamar la atenci\u00f3n de los ordinarios sobre el hecho de que en estos a\u00f1os un cierto n\u00famero de miembros del \u201cOpus Angelorum\u201d, entre los que se cuentan tambi\u00e9n sacerdotes que han salido o han sido expulsados de la Orden de los Can\u00f3nigos Regulares de la Santa Cruz, no han aceptado las normas dadas por este dicasterio e intentan restaurar lo que seg\u00fan ellos ser\u00eda el \u201caut\u00e9ntico Opus Angelorum\u201d&#8230;&#8221; <a href=\"http:\/\/visnews-es.blogspot.com\/2010\/11\/congregacion-doctrina-de-la-fe-sobre.html\">Click!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Tal como se presenta hoy, el \u201cOpus Angelorum\u201d es, por lo tanto, una asociaci\u00f3n p\u00fablica de la Iglesia en armon\u00eda con la doctrina tradicional y las normas de la suprema autoridad de la Iglesia. Ella difunde entre los fieles la devoci\u00f3n a los santos \u00e1ngeles, exhorta a rezar por los sacerdotes y promueve el amor &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fraynelson.com\/blog\/2010\/11\/09\/sobre-el-opus-angelorum\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;Sobre el Opus Angelorum&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[563,620,56],"tags":[],"class_list":["post-7753","post","type-post","status-publish","format-standard","hentry","category-angeles","category-enlaces","category-la-iglesia-hoy"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/7753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=7753"}],"version-history":[{"count":1,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/7753\/revisions"}],"predecessor-version":[{"id":7754,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/7753\/revisions\/7754"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=7753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=7753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=7753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}