{"id":66854,"date":"2018-11-19T16:01:58","date_gmt":"2018-11-19T21:01:58","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=66854"},"modified":"2018-11-13T19:00:31","modified_gmt":"2018-11-14T00:00:31","slug":"rosario-de-las-semanas-20181120","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2018\/11\/19\/rosario-de-las-semanas-20181120\/","title":{"rendered":"ROSARIO de las Semanas 20181120"},"content":{"rendered":"<p><div class=\"powerpress_player\" id=\"powerpress_player_6867\"><audio class=\"wp-audio-shortcode\" id=\"audio-66854-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa02.mp3?_=1\" \/><a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa02.mp3\">http:\/\/traffic.libsyn.com\/fraynelson\/rosa02.mp3<\/a><\/audio><\/div><p class=\"powerpress_links powerpress_links_mp3\" style=\"margin-bottom: 1px !important;\">Podcast: <a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa02.mp3\" class=\"powerpress_link_pinw\" target=\"_blank\" title=\"Play in new window\" onclick=\"return powerpress_pinw('https:\/\/fraynelson.com\/blog\/?powerpress_pinw=66854-podcast');\" rel=\"nofollow\">Play in new window<\/a> | <a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa02.mp3\" class=\"powerpress_link_d\" title=\"Download\" rel=\"nofollow\" download=\"rosa02.mp3\">Download<\/a><\/p><p class=\"powerpress_links powerpress_subscribe_links\">Subscribe: <a href=\"https:\/\/fraynelson.com\/blog\/feed\/podcast\/\" class=\"powerpress_link_subscribe powerpress_link_subscribe_rss\" target=\"_blank\" title=\"Subscribe via RSS\" rel=\"nofollow\">RSS<\/a><\/p>#RosarioFrayNelson para el <strong>Martes<\/strong>:<br \/>\nContemplamos los <em>Misterios de la Antigua Alianza<\/em><br \/>\n<iframe loading=\"lazy\" title=\"Rosario de las Semanas - Para los d\u00edas MARTES\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/TsCVbPXq4QY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><br \/>\nUsamos <a href=\"http:\/\/fraynelson.com\/oraciones.html\" target=\"_blank\" rel=\"noopener noreferrer\">esta versi\u00f3n de las oraciones<\/a>.<\/p>\n<ol>\n<li>En el primer misterio de la Antigua Alianza contemplamos <em>la paciencia de Dios, que no detuvo su amor ante el pecado de los hombres<\/em>.<\/li>\n<li>En el segundo misterio de la Antigua Alianza contemplamos <em>el camino de fe de Abraham<\/em>.<\/li>\n<li>En el tercer misterio de la Antigua Alianza contemplamos <em>el \u00e9xodo de la tierra de Egipto<\/em>.<\/li>\n<li>En el cuarto misterio de la Antigua Alianza contemplamos <em>el don de la Ley hecho a Mois\u00e9s y a su pueblo junto al Monte Sina\u00ed<\/em>.<\/li>\n<li>En el quinto misterio de la Antigua Alianza contemplamos <em>la gran promesa de Dios al rey David: que el cetro real no se apartar\u00eda de su descendencia<\/em>.<\/li>\n<li>En el sexto misterio de la Antigua Alianza contemplamos <em>la valiente vocaci\u00f3n de los profetas, por quienes el Esp\u00edritu Santo nos habl\u00f3 de muchas maneras<\/em>.<\/li>\n<li>En el s\u00e9ptimo misterio de la Antigua Alianza contemplamos a <em>el peque\u00f1o resto de Israel, que permaneci\u00f3 fiel y fue semilla de la Nueva y Eterna Alianza<\/em>.<\/li>\n<\/ol>\n<p>[<strong>REPRODUCCI\u00d3N PERMITIDA<\/strong> \u2013 Este es un ejercicio privado de devoci\u00f3n &#8220;<em>ad experimentum<\/em>&#8221; en proceso de aprobaci\u00f3n oficial. Puede divulgarse en las redes sociales, blogs, emisoras de radio, y otros medios siempre que al mismo tiempo se haga la presente advertencia.]<\/p>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1140,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,1265],"tags":[],"class_list":["post-66854","post","type-post","status-publish","format-standard","hentry","category-audio","category-rosario-de-las-semanas"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/66854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1140"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=66854"}],"version-history":[{"count":1,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/66854\/revisions"}],"predecessor-version":[{"id":66860,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/66854\/revisions\/66860"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=66854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=66854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=66854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}