{"id":65711,"date":"2018-09-30T11:19:39","date_gmt":"2018-09-30T16:19:39","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=65711"},"modified":"2018-09-29T11:21:42","modified_gmt":"2018-09-29T16:21:42","slug":"entregan-premios-religion-en-libertad-a-la-promocion-de-la-fe-catolica","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2018\/09\/30\/entregan-premios-religion-en-libertad-a-la-promocion-de-la-fe-catolica\/","title":{"rendered":"Entregan premios Religi\u00f3n En Libertad a la promoci\u00f3n de la fe cat\u00f3lica"},"content":{"rendered":"<p>&#8220;El jueves 27 de septiembre tuvo lugar la primera entrega de los Premios Religi\u00f3n en Libertad que reconocen \u201ca personalidades que de forma p\u00fablica promueven la fe cat\u00f3lica, llevan a cabo obras evangelizadoras y caritativas o, a trav\u00e9s de la cultura, la educaci\u00f3n o la ciencia, extienden la vida cristiana\u201d&#8230;&#8221;<\/p>\n<p><a href=\"https:\/\/www.evernote.com\/shard\/s254\/sh\/6f3a4163-113d-473e-a53f-5c86fc080162\/5f5fd9db7c8fc788a8d1b3d0ba2e77f3\" rel=\"noopener\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/fraynelson.com\/banco_imagenes\/recomendados\/20181002.jpg\" alt=\"\" \/><\/p>\n<p>Haz clic aqu\u00ed!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;El jueves 27 de septiembre tuvo lugar la primera entrega de los Premios Religi\u00f3n en Libertad que reconocen \u201ca personalidades que de forma p\u00fablica promueven la fe cat\u00f3lica, llevan a cabo obras evangelizadoras y caritativas o, a trav\u00e9s de la cultura, la educaci\u00f3n o la ciencia, extienden la vida cristiana\u201d&#8230;&#8221; Haz clic aqu\u00ed!<\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[620,56],"tags":[],"class_list":["post-65711","post","type-post","status-publish","format-standard","hentry","category-enlaces","category-la-iglesia-hoy"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/65711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=65711"}],"version-history":[{"count":2,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/65711\/revisions"}],"predecessor-version":[{"id":75117,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/65711\/revisions\/75117"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=65711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=65711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=65711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}