{"id":6154,"date":"2010-06-12T00:01:32","date_gmt":"2010-06-12T05:01:32","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=6154"},"modified":"2010-06-11T23:19:06","modified_gmt":"2010-06-12T04:19:06","slug":"junio-12-la-total-dependencia-de-dios","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2010\/06\/12\/junio-12-la-total-dependencia-de-dios\/","title":{"rendered":"Junio 12: La total dependencia de Dios"},"content":{"rendered":"<p>Homilia para el\u00a0 s\u00e1bado de la\u00a0decima \u00a0semana del Tiempo Ordinario, con una invitacion a ponernos en las manos de Dios<\/p>\n<p>[<em>Si est\u00e1s leyendo esto en <strong>Facebook<\/strong> y deseas escuchar la predicaci\u00f3n a la que aqu\u00ed se hace referencia, haz click en &#8220;Publicaci\u00f3n Original.&#8221;]<\/em><\/p>\n<div class=\"powerpress_player\" id=\"powerpress_player_5121\"><audio class=\"wp-audio-shortcode\" id=\"audio-6154-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/fraynelson.com\/homilias_mp3\/o106002a.mp3?_=1\" \/><a href=\"http:\/\/fraynelson.com\/homilias_mp3\/o106002a.mp3\">http:\/\/fraynelson.com\/homilias_mp3\/o106002a.mp3<\/a><\/audio><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Homilia para el\u00a0 s\u00e1bado de la\u00a0decima \u00a0semana del Tiempo Ordinario, con una invitacion a ponernos en las manos de Dios [Si est\u00e1s leyendo esto en Facebook y deseas escuchar la predicaci\u00f3n a la que aqu\u00ed se hace referencia, haz click en &#8220;Publicaci\u00f3n Original.&#8221;]<\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[456,364,291,307],"tags":[],"class_list":["post-6154","post","type-post","status-publish","format-standard","hentry","category-accion_de_gracias","category-amor_de_dios","category-audio","category-homilias"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/6154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=6154"}],"version-history":[{"count":2,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/6154\/revisions"}],"predecessor-version":[{"id":6156,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/6154\/revisions\/6156"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=6154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=6154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=6154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}