{"id":59449,"date":"2018-01-04T12:40:26","date_gmt":"2018-01-04T17:40:26","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=59449"},"modified":"2017-12-27T09:11:02","modified_gmt":"2017-12-27T14:11:02","slug":"la-gracia-del-sabado-6-de-enero-de-2018","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2018\/01\/04\/la-gracia-del-sabado-6-de-enero-de-2018\/","title":{"rendered":"LA GRACIA del S\u00e1bado 6 de Enero de 2018"},"content":{"rendered":"<p>Pidamos ser movidos por el Esp\u00edritu Santo para empezar una vida nueva, reconociendo que somos pecadores y a la vez amados y perdonados por Dios.<\/p>\n<p><iframe loading=\"lazy\" title=\"LA GRACIA del S\u00e1bado 6 de Enero de 2018\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/VM0lwuqsVM4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>[REPRODUCCI\u00d3N PERMITIDA \u2013 Ay\u00fadanos a divulgar este archivo de audio en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pidamos ser movidos por el Esp\u00edritu Santo para empezar una vida nueva, reconociendo que somos pecadores y a la vez amados y perdonados por Dios. [REPRODUCCI\u00d3N PERMITIDA \u2013 Ay\u00fadanos a divulgar este archivo de audio en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"author":1140,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,366,307,841,350,302],"tags":[],"class_list":["post-59449","post","type-post","status-publish","format-standard","hentry","category-audio","category-espiritu_santo","category-homilias","category-micro-homilias","category-vida_nueva","category-video"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/59449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1140"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=59449"}],"version-history":[{"count":2,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/59449\/revisions"}],"predecessor-version":[{"id":59487,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/59449\/revisions\/59487"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=59449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=59449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=59449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}