{"id":5255,"date":"2010-03-19T00:01:14","date_gmt":"2010-03-19T05:01:14","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=5255"},"modified":"2010-03-17T21:57:43","modified_gmt":"2010-03-18T02:57:43","slug":"marzo-19-san-jose-un-hombre-ejemplar","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2010\/03\/19\/marzo-19-san-jose-un-hombre-ejemplar\/","title":{"rendered":"Marzo 19: San Jose, un hombre ejemplar"},"content":{"rendered":"<p>Homilia para el dia de la Solemnidad de San Jose, nos exhorta a ser como San Jose: puros y leales con Dios<\/p>\n<p>\u00a0[<em>Si est\u00e1s leyendo esto en <strong>Facebook <\/strong>y deseas escuchar la predicaci\u00f3n a la que aqu\u00ed se hace referencia, haz click en Publicaci\u00f3n Original<\/em>.&#8221;]<\/p>\n<p>[podcast]http:\/\/fraynelson.com\/homilias_mp3\/sjos006a.mp3[\/podcast]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Homilia para el dia de la Solemnidad de San Jose, nos exhorta a ser como San Jose: puros y leales con Dios \u00a0[Si est\u00e1s leyendo esto en Facebook y deseas escuchar la predicaci\u00f3n a la que aqu\u00ed se hace referencia, haz click en Publicaci\u00f3n Original.&#8221;] [podcast]http:\/\/fraynelson.com\/homilias_mp3\/sjos006a.mp3[\/podcast]<\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,307,647,553],"tags":[],"class_list":["post-5255","post","type-post","status-publish","format-standard","hentry","category-audio","category-homilias","category-san_jose","category-santidad"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/5255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=5255"}],"version-history":[{"count":4,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/5255\/revisions"}],"predecessor-version":[{"id":5259,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/5255\/revisions\/5259"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=5255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=5255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=5255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}