{"id":47018,"date":"2016-08-12T15:03:35","date_gmt":"2016-08-12T20:03:35","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=47018"},"modified":"2016-08-11T16:06:07","modified_gmt":"2016-08-11T21:06:07","slug":"que-significa-la-expresion-expandir-la-consciencia","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2016\/08\/12\/que-significa-la-expresion-expandir-la-consciencia\/","title":{"rendered":"\u00bfQu\u00e9 significa la expresi\u00f3n \u201cexpandir la consciencia\u201d?"},"content":{"rendered":"<p>&#8220;\u00bfQu\u00e9 significa la expresi\u00f3n \u201cexpandir la consciencia\u201d? Una cuesti\u00f3n que est\u00e1 de actualidad, ya que se multiplican las ofertas de nuevas espiritualidades que proponen este objetivo. \u00bfSe trata de algo aceptable para un cat\u00f3lico? Vicente Jara, laico dominico y miembro de la Red Iberoamericana de Estudio de las Sectas (RIES), lo tiene claro: es algo totalmente alejado de la religiosidad cristiana y de su sentido antropol\u00f3gico del ser humano&#8230;&#8221;<\/p>\n<p><a href=\"https:\/\/www.evernote.com\/shard\/s254\/sh\/7a1e3316-c573-4f21-8c35-695c12cc5acc\/0453174e8fac82aab336825ec55430d3\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/fraynelson.com\/banco_imagenes\/recomendados\/20160814.jpg\" alt=\"\" \/><\/p>\n<p>Haz click aqu\u00ed!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;\u00bfQu\u00e9 significa la expresi\u00f3n \u201cexpandir la consciencia\u201d? Una cuesti\u00f3n que est\u00e1 de actualidad, ya que se multiplican las ofertas de nuevas espiritualidades que proponen este objetivo. \u00bfSe trata de algo aceptable para un cat\u00f3lico? Vicente Jara, laico dominico y miembro de la Red Iberoamericana de Estudio de las Sectas (RIES), lo tiene claro: es algo &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fraynelson.com\/blog\/2016\/08\/12\/que-significa-la-expresion-expandir-la-consciencia\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;\u00bfQu\u00e9 significa la expresi\u00f3n \u201cexpandir la consciencia\u201d?&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[623,620,484],"tags":[],"class_list":["post-47018","post","type-post","status-publish","format-standard","hentry","category-apologetica-sectas","category-enlaces","category-nueva_era"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/47018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=47018"}],"version-history":[{"count":1,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/47018\/revisions"}],"predecessor-version":[{"id":47019,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/47018\/revisions\/47019"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=47018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=47018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=47018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}