{"id":41812,"date":"2016-01-20T01:11:49","date_gmt":"2016-01-20T06:11:49","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=41812"},"modified":"2016-01-19T16:16:19","modified_gmt":"2016-01-19T21:16:19","slug":"destruccion-de-idolos-y-templos","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2016\/01\/20\/destruccion-de-idolos-y-templos\/","title":{"rendered":"Destrucci\u00f3n de \u00eddolos y templos"},"content":{"rendered":"<p>Este grave tema fue estudiado por el jesu\u00edta Constantino Bayle en<i> Los cl\u00e9rigos y la extirpaci\u00f3n de la idolatr\u00eda entre los ne\u00f3fitos americanos,<\/i> y por el franciscano Pedro Borges en <i>La extirpaci\u00f3n de la idolatr\u00eda en Indias como m\u00e9todo misional (siglo XVI)<\/i>. Aqu\u00ed lo consideraremos nosotros en la primera evangelizaci\u00f3n de M\u00e9xico.<\/p>\n<p>En efecto, a poco de la conquista (1519 -1523), seg\u00fan nos cuenta el P. Motolin\u00eda, \u00aben todos los templos de los \u00eddolos, si no era en algunos derribados y quemados en M\u00e9xico, en los de la tierra, y a\u00fan en los del mismo M\u00e9xico, eran servidos y honrados los demonios. Ocupados los espa\u00f1oles en edificar a M\u00e9xico y en hacer casas y moradas para s\u00ed, content\u00e1banse con que no hubiese delante de ellos sacrificio de homicidio p\u00fablico, que escondidos y a la redonda de M\u00e9xico no faltaban; y de esta manera se estaba la idolatr\u00eda en paz\u00bb (I,3, 64).<\/p>\n<p>Los espa\u00f1oles civiles, por otra parte, ten\u00edan \u00abtemor \u2013cuenta Mendieta\u2013 de que los indios se alborotasen y levantasen contra ellos. Y como eran pocos y el Gobernador ausente [Cort\u00e9s en la expedici\u00f3n a las Hibueras], los matasen a todos que este temor por muchos a\u00f1os dur\u00f3 entre los espa\u00f1oles seglares, mas no entre los frailes\u00bb (III,21).<\/p>\n<p>As\u00ed las cosas, los frailes ve\u00edan que la evangelizaci\u00f3n no pod\u00eda ir adelante en tanto que los \u00eddolos e idolillos siguieran ejerciendo su mal\u00e9fico influjo, y mientras los <i>teocalis<\/i>, aunque ya limpios de las siniestras alfombras de sangre humana que en otro tiempo ostentaban, continuaran erguidos en toda su grandiosidad. Y cuenta Motolin\u00eda que el 1 de enero de 1525, en Tetzcoco, tres frailes \u00abespantaron y ahuyentaron todos los que estaban en las casas y salas de los demonios\u00bb, y la batalla en seguida prendi\u00f3 en M\u00e9xico, Cuauh-titl\u00e1n y al rededores.<\/p>\n<p>\u00abY luego, casi a la par, en Tlaxcallan comenzaron a derribar y a destruir \u00eddolos\u00bb, poniendo en su lugar la Cruz y una imagen de Santa Mar\u00eda. M\u00e1s a\u00fan, los frailes, con los indios cristianos, \u00abpara hacer las iglesias comenzaron a echar mano de sus <i>teocalis<\/i> para sacar de ellos piedra y madera, y de esta manera quedaron desollados y derribados; y los \u00eddolos de piedra, de los cuales hab\u00eda infinitos, no s\u00f3lo escaparon quebrados y hechos pedazos, pero vinieron a servir de cimiento para las iglesias\u00bb (III,3, 64).<\/p>\n<p>Indios y espa\u00f1oles humillaron as\u00ed a los dioses de aquellos inmensos <i>mataderos de hombres<\/i>, donde hab\u00edan visto matar, descuartizar y desollar a muchos de sus parientes y amigos.<\/p>\n<hr \/>\n<p><em>El autor de esta obra es el sacerdote espa\u00f1ol Jos\u00e9 Ma. Iraburu, a quien expresamos nuestra gratitud. Aqu\u00ed la obra se publica \u00edntegra, por entregas. Lo ya publicado puede consultarse<\/em> <a href=\"http:\/\/is.gd\/iglesiamerica\">aqu\u00ed<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este grave tema fue estudiado por el jesu\u00edta Constantino Bayle en Los cl\u00e9rigos y la extirpaci\u00f3n de la idolatr\u00eda entre los ne\u00f3fitos americanos, y por el franciscano Pedro Borges en La extirpaci\u00f3n de la idolatr\u00eda en Indias como m\u00e9todo misional (siglo XVI). Aqu\u00ed lo consideraremos nosotros en la primera evangelizaci\u00f3n de M\u00e9xico. En efecto, a &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fraynelson.com\/blog\/2016\/01\/20\/destruccion-de-idolos-y-templos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;Destrucci\u00f3n de \u00eddolos y templos&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1098,783],"tags":[],"class_list":["post-41812","post","type-post","status-publish","format-standard","hentry","category-hechos-de-los-apostoles-de-america","category-mexico"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/41812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=41812"}],"version-history":[{"count":2,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/41812\/revisions"}],"predecessor-version":[{"id":41814,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/41812\/revisions\/41814"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=41812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=41812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=41812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}