{"id":39932,"date":"2015-11-13T14:31:39","date_gmt":"2015-11-13T19:31:39","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=39932"},"modified":"2015-11-07T21:52:28","modified_gmt":"2015-11-08T02:52:28","slug":"completas-20151113","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2015\/11\/13\/completas-20151113\/","title":{"rendered":"COMPLETAS 20151113"},"content":{"rendered":"<p>#CompletasFrayNelson para el <strong>Viernes<\/strong><\/p>\n<p><a href=\"https:\/\/fraynelson.com\/blog\/wp-content\/uploads\/2015\/11\/bo32_completas.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fraynelson.com\/blog\/wp-content\/uploads\/2015\/11\/bo32_completas.jpg\" alt=\"bo32_completas\" width=\"400\" height=\"400\" class=\"aligncenter size-full wp-image-39891\" \/><\/a><\/p>\n<div class=\"powerpress_player\" id=\"powerpress_player_1006\"><audio class=\"wp-audio-shortcode\" id=\"audio-39932-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/fraynelson.com\/conferencias\/oracion\/comp05.mp3?_=1\" \/><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/comp05.mp3\">http:\/\/fraynelson.com\/conferencias\/oracion\/comp05.mp3<\/a><\/audio><\/div>\n<p>[REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este camino de oraci\u00f3n en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#CompletasFrayNelson para el Viernes [REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este camino de oraci\u00f3n en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,1218,413],"tags":[],"class_list":["post-39932","post","type-post","status-publish","format-standard","hentry","category-audio","category-completas","category-oracion"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/39932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=39932"}],"version-history":[{"count":2,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/39932\/revisions"}],"predecessor-version":[{"id":39942,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/39932\/revisions\/39942"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=39932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=39932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=39932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}