{"id":38920,"date":"2015-10-02T16:39:48","date_gmt":"2015-10-02T21:39:48","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=38920"},"modified":"2015-10-02T12:04:55","modified_gmt":"2015-10-02T17:04:55","slug":"la-gracia-del-domingo-4-de-octubre-de-2015-2","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2015\/10\/02\/la-gracia-del-domingo-4-de-octubre-de-2015-2\/","title":{"rendered":"LA GRACIA del Domingo 4 de Octubre de 2015"},"content":{"rendered":"<p>DOMINGO XXVII DEL TIEMPO ORDINARIO, CICLO B<\/p>\n<p>El divorcio trae da\u00f1os irreparables a la sociedad, oremos para que el matrimonio no se degrade y por el contrario se cumpla a trav\u00e9s de este hermoso sacramento el Plan de Dios.<\/p>\n<div class=\"powerpress_player\" id=\"powerpress_player_9329\"><audio class=\"wp-audio-shortcode\" id=\"audio-38920-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/dl.dropboxusercontent.com\/u\/15652\/homilias_mp3\/20151004.mp3?_=1\" \/><a href=\"https:\/\/dl.dropboxusercontent.com\/u\/15652\/homilias_mp3\/20151004.mp3\">https:\/\/dl.dropboxusercontent.com\/u\/15652\/homilias_mp3\/20151004.mp3<\/a><\/audio><\/div>\n<p><iframe loading=\"lazy\" title=\"LA GRACIA del Domingo 4 de Octubre de 2015\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/-dSg6_TlQKY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>[REPRODUCCI\u00d3N PERMITIDA \u2013 Ay\u00fadanos a divulgar este archivo de audio en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DOMINGO XXVII DEL TIEMPO ORDINARIO, CICLO B El divorcio trae da\u00f1os irreparables a la sociedad, oremos para que el matrimonio no se degrade y por el contrario se cumpla a trav\u00e9s de este hermoso sacramento el Plan de Dios. [REPRODUCCI\u00d3N PERMITIDA \u2013 Ay\u00fadanos a divulgar este archivo de audio en las redes sociales, blogs, emisoras &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fraynelson.com\/blog\/2015\/10\/02\/la-gracia-del-domingo-4-de-octubre-de-2015-2\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;LA GRACIA del Domingo 4 de Octubre de 2015&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1139,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,307,841,453,302],"tags":[],"class_list":["post-38920","post","type-post","status-publish","format-standard","hentry","category-audio","category-homilias","category-micro-homilias","category-pareja","category-video"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/38920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1139"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=38920"}],"version-history":[{"count":3,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/38920\/revisions"}],"predecessor-version":[{"id":38974,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/38920\/revisions\/38974"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=38920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=38920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=38920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}