{"id":38838,"date":"2015-10-02T00:01:02","date_gmt":"2015-10-02T05:01:02","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=38838"},"modified":"2015-09-26T12:59:34","modified_gmt":"2015-09-26T17:59:34","slug":"laudes-20151002","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2015\/10\/02\/laudes-20151002\/","title":{"rendered":"LAUDES 20151002"},"content":{"rendered":"<p>#LaudesFrayNelson para la <strong>Memoria de los Santos \u00c1ngeles Custodios<\/strong><\/p>\n<p><a href=\"https:\/\/fraynelson.com\/blog\/wp-content\/uploads\/2015\/09\/angel_guardian.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fraynelson.com\/blog\/wp-content\/uploads\/2015\/09\/angel_guardian.jpg\" alt=\"angel_guardian\" width=\"400\" height=\"588\" class=\"aligncenter size-full wp-image-38855\" \/><\/a><\/p>\n<div class=\"powerpress_player\" id=\"powerpress_player_3902\"><audio class=\"wp-audio-shortcode\" id=\"audio-38838-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/fraynelson.com\/conferencias\/oracion\/sacua.mp3?_=1\" \/><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/sacua.mp3\">http:\/\/fraynelson.com\/conferencias\/oracion\/sacua.mp3<\/a><\/audio><\/div>\n<p>[REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este camino de oraci\u00f3n en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#LaudesFrayNelson para la Memoria de los Santos \u00c1ngeles Custodios [REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este camino de oraci\u00f3n en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,1096,413],"tags":[],"class_list":["post-38838","post","type-post","status-publish","format-standard","hentry","category-audio","category-laudes","category-oracion"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/38838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=38838"}],"version-history":[{"count":2,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/38838\/revisions"}],"predecessor-version":[{"id":38869,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/38838\/revisions\/38869"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=38838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=38838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=38838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}