{"id":359,"date":"2004-09-10T01:03:41","date_gmt":"2004-09-10T06:03:41","guid":{"rendered":"1058268150"},"modified":"2005-09-13T09:13:02","modified_gmt":"2005-09-13T09:13:02","slug":"376","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2004\/09\/10\/376\/","title":{"rendered":"No me esperaste, Joe&#8230;"},"content":{"rendered":"<p>Me llamaba la atenci\u00f3n que a tu edad, ya avanzada y tan venerable, manifestaras tanta prisa en todo: fuera el servicio a Dios o a tus hermanos. Yo pienso que sent\u00edas en alg\u00fan lugar de tu coraz\u00f3n que el tiempo no ser\u00eda muy largo y por eso te propusiste ser el primero en acogerme como un genuino hermano, dedicando de tu tiempo y tu saludo a este suramericano medio inc\u00f3gnito, t\u00edmido, titubeante en su ingl\u00e9s, inseguro en una nueva cultura. Me regalaste el \u00faltimo tesoro que te quedaba, despu\u00e9s de m\u00e1s de ochenta a\u00f1os de vida y cincuenta de sacerdocio ejemplar: me diste de tu tiempo; y tambi\u00e9n de tu alegr\u00eda, de tu experiencia.<\/p>\n<p><!--more--><\/p>\n<p>Pero no me esperaste, Joe. Poco antes de partir para California y para Colombia, apenas entrado el mes de agosto, fui a confesarme contigo. Me atendiste con la seriedad y la dulzura que ten\u00eda y tiene Cristo para ti. Nos despedimos sabiendo que tambi\u00e9n a ti te aguardaba un viaje, un \u00faltimo viaje en esta tierra: a Lourdes, tierra de Mar\u00eda, de quien qued\u00f3 prendado tu coraz\u00f3n hace muchos a\u00f1os. Y cada uno sali\u00f3 a su destino: Estados Unidos para m\u00ed, Francia para ti. Volviste primero que yo, porque ten\u00edas prisa, porque te esperaba Dubl\u00edn, pero sobre todo porque te esperaba la \u00faltima y decisiva cita, aquella que todos tenemos desde que nacemos, el encuentro decisivo con Cristo al umbral de la muerte.<\/p>\n<p>Me dicen que todav\u00eda en la \u00faltima noche, la de aquel domingo, te afanabas con caridad tratando de atender a quienes llamaban por tel\u00e9fono. \u00a1Dios! \u00bfQui\u00e9n oy\u00f3 tus \u00faltimas palabras? Una se\u00f1ora que estaba buscando a otro padre. Hiciste el oficio de portero y recepcionista poco antes de irte a recoger esa noche, y todos te vieron llegar a tu habitaci\u00f3n pero s\u00f3lo Cristo supo la hora en que saliste de ella. Todos sab\u00edan que estabas cansado, agotado, Joe; s\u00f3lo Cristo sab\u00eda que estaba tan pr\u00f3ximo tu descanso.<\/p>\n<p>\u00bfSabes? Me alegro por ti. T\u00fa ya llegaste. Tu premio es ya seguro; tu alegr\u00eda, perfecta; tu sacerdocio, colmado. Tus ojos ya pueden descansar de ver a los pobres, a los inmigrantes, a los enfermos, a todos en los que buscaste afanoso a Jes\u00fas; ahora es Jes\u00fas quien te mira, quien te cuida, quien te mima. Me alegro por ti. Pero me da pesar que no me hayas esperado. Un correo del padre prior me dijo que no estar\u00edas, que te hab\u00edas ido. Tampoco \u00e9l pudo despedirte. Creo que tuviste prisa tambi\u00e9n en eso, en la manera de partir.<\/p>\n<p>Joe, me vas a hacer falta. No est\u00e1 lleno el mundo de personas como t\u00fa, y el mundo necesita de gente as\u00ed. Dile a Jes\u00fas eso: que env\u00ede mucha gente como t\u00fa. Y prom\u00e9teme que un d\u00eda celebraremos juntos la Misa de la Eternidad. Un abrazo, padre y hermano: te recuerdo y te quiero mucho.<\/p>\n<p>Joe Moran, OP: descansa en paz!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Me llamaba la atenci\u00f3n que a tu edad, ya avanzada y tan venerable, manifestaras tanta prisa en todo: fuera el servicio a Dios o a tus hermanos. Yo pienso que sent\u00edas en alg\u00fan lugar de tu coraz\u00f3n que el tiempo no ser\u00eda muy largo y por eso te propusiste ser el primero en acogerme como &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fraynelson.com\/blog\/2004\/09\/10\/376\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;No me esperaste, Joe&#8230;&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-359","post","type-post","status-publish","format-standard","hentry","category-personas"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=359"}],"version-history":[{"count":0,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/359\/revisions"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}