{"id":34945,"date":"2015-04-11T12:56:02","date_gmt":"2015-04-11T17:56:02","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=34945"},"modified":"2015-04-07T18:07:56","modified_gmt":"2015-04-07T23:07:56","slug":"la-gracia-del-lunes-13-de-abril-de-2015","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2015\/04\/11\/la-gracia-del-lunes-13-de-abril-de-2015\/","title":{"rendered":"LA GRACIA del Lunes 13 de Abril de 2015"},"content":{"rendered":"<p>El coraz\u00f3n humano es insaciable y por ello no necesita peque\u00f1os parches sino nacer de nuevo.<\/p>\n<div class=\"powerpress_player\" id=\"powerpress_player_609\"><audio class=\"wp-audio-shortcode\" id=\"audio-34945-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/dl.dropboxusercontent.com\/u\/15652\/homilias_mp3\/20150413.mp3?_=1\" \/><a href=\"https:\/\/dl.dropboxusercontent.com\/u\/15652\/homilias_mp3\/20150413.mp3\">https:\/\/dl.dropboxusercontent.com\/u\/15652\/homilias_mp3\/20150413.mp3<\/a><\/audio><\/div>\n<p><iframe loading=\"lazy\" title=\"LA GRACIA del Lunes 13 de Abril de 2015\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/vX_dgd9iNWE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>[REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este archivo de audio en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El coraz\u00f3n humano es insaciable y por ello no necesita peque\u00f1os parches sino nacer de nuevo. [REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este archivo de audio en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,307,841,350,302],"tags":[],"class_list":["post-34945","post","type-post","status-publish","format-standard","hentry","category-audio","category-homilias","category-micro-homilias","category-vida_nueva","category-video"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/34945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=34945"}],"version-history":[{"count":2,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/34945\/revisions"}],"predecessor-version":[{"id":34960,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/34945\/revisions\/34960"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=34945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=34945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=34945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}