{"id":33613,"date":"2015-02-10T14:32:20","date_gmt":"2015-02-10T19:32:20","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=33613"},"modified":"2015-02-10T14:32:20","modified_gmt":"2015-02-10T19:32:20","slug":"escucha-meditacion-sobre-los-salmos-llamados-de-las-subidas","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2015\/02\/10\/escucha-meditacion-sobre-los-salmos-llamados-de-las-subidas\/","title":{"rendered":"ESCUCHA, Meditaci\u00f3n sobre los Salmos llamados de las Subidas"},"content":{"rendered":"<p><strong>Escuela de Vida Interior, Tema 35<\/strong>: Meditaci\u00f3n sobre los Salmos llamados de las Subidas<\/p>\n<p>* Texto utilizado como ejemplo, el Salmo 122:<\/p>\n<blockquote><p>\u00a1Qu\u00e9 alegr\u00eda cuando me dijeron:<br \/>\n\u00abVamos a la casa del Se\u00f1or\u00bb!<br \/>\nYa est\u00e1n pisando nuestros pies<br \/>\ntus umbrales, Jerusal\u00e9n.<\/p>\n<p>Jerusal\u00e9n est\u00e1 fundada<br \/>\ncomo ciudad bien compacta.<br \/>\nAll\u00e1 suben las tribus,<br \/>\nlas tribus del Se\u00f1or,<\/p>\n<p>seg\u00fan la costumbre de Israel,<br \/>\na celebrar el nombre del Se\u00f1or;<br \/>\nen ella est\u00e1n los tribunales de justicia,<br \/>\nen el palacio de David.<\/p>\n<p>Desead la paz a Jerusal\u00e9n:<br \/>\n\u00abVivan seguros los que te aman,<br \/>\nhaya paz dentro de tus muros,<br \/>\nseguridad en tus palacios\u00bb.<\/p>\n<p>Por mis hermanos y compa\u00f1eros,<br \/>\nvoy a decir: \u00abLa paz contigo\u00bb.<br \/>\nPor la casa del Se\u00f1or, nuestro Dios,<br \/>\nte deseo todo bien. <\/p><\/blockquote>\n<p>* Para evitar desviaciones doctrinales y usos inapropiados del lenguaje celebrativo de los sacrificios, el Libro del Deuteronomio prescribi\u00f3 que s\u00f3lo hubiera u lugar de culto: el templo de Jerusal\u00e9n.<\/p>\n<p>* Esto hizo que los israelitas organizaran su vida introduciendo un elemento nuevo: peregrinaciones a la Ciudad Santa. Y como Jerusal\u00e9n est\u00e1 construida al modo de las ciudades antiguas, en una colina para ser mejor defendida, esas peregrinaciones ten\u00edan la estructura de un ascenso, una &#8220;subida,&#8221; y por ello los salmos que por costumbre serv\u00edan para acompa\u00f1ar las jornadas de los peregrinos son llamados &#8220;salmos de las subidas.&#8221;<\/p>\n<p>* Conviene recordar la dureza de esos largos trayectos que supon\u00edan abundantes sacrificios pero que a la vez afianzaban la fe del pueblo y su cohesi\u00f3n como naci\u00f3n elegida por Dios.<\/p>\n<p>* Por eso podemos asegurar que hay bienes permanentes que est\u00e1n inscritos en estos salmos, entre los cuales es ampliamente conocido el 122. En s\u00edntesis, de ellos recibimos:<\/p>\n<p>(1) Al peregrinar retomamos conciencia del car\u00e1cter comunitario de nuestra fe.<\/p>\n<p>(2) Peregrinar nos ayuda a tomar conciencia de c\u00f3mo habremos de desprendernos de todo y quedarnos con lo esencial.<\/p>\n<p>(3) Los lugares significativos nos ayudan a recordar que hay una meta en la vida.<\/p>\n<p>* * *<\/p>\n<p><em>Este tema pertenece al <strong>Cap\u00edtulo 04<\/strong> de la Escuela de Vida Interior; la serie completa de los diez temas de este <strong>Cap\u00edtulo 04<\/strong> se est\u00e1 publicando aqu\u00ed:<\/em><\/p>\n<p><code><a href=\"http:\/\/is.gd\/vida_interior_04\">is.gd\/vida_interior_04<\/a><\/code><\/p>\n<p><em>La serie de <strong>TODOS<\/strong> los temas de esta Escuela de Vida Interior est\u00e1 aqu\u00ed<\/em>:<\/p>\n<p><code><a href=\"http:\/\/is.gd\/vidainterior\">is.gd\/vidainterior<\/a><\/code><\/p>\n<div class=\"powerpress_player\" id=\"powerpress_player_5664\"><audio class=\"wp-audio-shortcode\" id=\"audio-33613-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/fraynelson.com\/conferencias\/madurez\/escuela_de_vida_interior_35_meditacion_sobre_el_salmo_122.mp3?_=1\" \/><a href=\"http:\/\/fraynelson.com\/conferencias\/madurez\/escuela_de_vida_interior_35_meditacion_sobre_el_salmo_122.mp3\">http:\/\/fraynelson.com\/conferencias\/madurez\/escuela_de_vida_interior_35_meditacion_sobre_el_salmo_122.mp3<\/a><\/audio><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Escuela de Vida Interior, Tema 35: Meditaci\u00f3n sobre los Salmos llamados de las Subidas * Texto utilizado como ejemplo, el Salmo 122: \u00a1Qu\u00e9 alegr\u00eda cuando me dijeron: \u00abVamos a la casa del Se\u00f1or\u00bb! Ya est\u00e1n pisando nuestros pies tus umbrales, Jerusal\u00e9n. Jerusal\u00e9n est\u00e1 fundada como ciudad bien compacta. All\u00e1 suben las tribus, las tribus del &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fraynelson.com\/blog\/2015\/02\/10\/escucha-meditacion-sobre-los-salmos-llamados-de-las-subidas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;ESCUCHA, Meditaci\u00f3n sobre los Salmos llamados de las Subidas&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,275,775,329,1171],"tags":[],"class_list":["post-33613","post","type-post","status-publish","format-standard","hentry","category-audio","category-devociones-y-novenas","category-jerusalen","category-salmos","category-vida-interior-04"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/33613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=33613"}],"version-history":[{"count":2,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/33613\/revisions"}],"predecessor-version":[{"id":33615,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/33613\/revisions\/33615"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=33613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=33613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=33613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}