{"id":3323,"date":"2007-09-20T04:43:00","date_gmt":"2007-09-20T09:43:00","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=3323"},"modified":"2009-09-29T22:15:40","modified_gmt":"2009-09-30T03:15:40","slug":"la-escuela-de-la-sabiduria-15-de-32","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2007\/09\/20\/la-escuela-de-la-sabiduria-15-de-32\/","title":{"rendered":"La Escuela de la Sabidur\u00eda (15 de 32)"},"content":{"rendered":"<p>[podcast]http:\/\/fraynelson.com\/conferencias\/biblia\/pv15_arrepentimiento_y_autoestima_cp.mp3[\/podcast]<\/p>\n<p><b>Resumen del curso<\/b>: Una serie de predicaciones sobre el mensaje de la Sagrada Escritura aplicado a nuestro tiempo y nuestro mundo. Material acompa\u00f1ante <a href=\"http:\/\/fraynelson.com\/biblioteca\/biblia\/escuela.html\" target=\"_blank\">aqu\u00ed<\/a>. <b>Tema 15<\/b>: Arrepentimiento y autoestima<\/p>\n<p>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[podcast]http:\/\/fraynelson.com\/conferencias\/biblia\/pv15_arrepentimiento_y_autoestima_cp.mp3[\/podcast] Resumen del curso: Una serie de predicaciones sobre el mensaje de la Sagrada Escritura aplicado a nuestro tiempo y nuestro mundo. Material acompa\u00f1ante aqu\u00ed. Tema 15: Arrepentimiento y autoestima .<\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[435,444,446,291,445,297,322,434,436],"tags":[],"class_list":["post-3323","post","type-post","status-publish","format-standard","hentry","category-435","category-amistad","category-arrepentimiento","category-audio","category-autoridad","category-biblia","category-conversion","category-434","category-sabiduria"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/3323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=3323"}],"version-history":[{"count":0,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/3323\/revisions"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=3323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=3323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=3323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}