{"id":32662,"date":"2014-12-27T00:05:35","date_gmt":"2014-12-27T05:05:35","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=32662"},"modified":"2014-12-26T23:19:12","modified_gmt":"2014-12-27T04:19:12","slug":"laudes-visperas-para-la-semana-del-28-de-diciembre-de-2014-al-3-de-enero-de-2015","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2014\/12\/27\/laudes-visperas-para-la-semana-del-28-de-diciembre-de-2014-al-3-de-enero-de-2015\/","title":{"rendered":"Laudes &#038; V\u00edsperas para la semana del 28 de Diciembre de 2014 al 3 de Enero de 2015"},"content":{"rendered":"<p><a href=\"https:\/\/fraynelson.com\/blog\/wp-content\/uploads\/2014\/08\/citara.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fraynelson.com\/blog\/wp-content\/uploads\/2014\/08\/citara-209x300.jpg\" alt=\"citara\" width=\"209\" height=\"300\" class=\"aligncenter size-medium wp-image-29583\" \/><\/a><\/p>\n<p><strong>Domingo 28 de Diciembre<\/strong>: Fiesta de la Sagrada Familia, Ciclo B<\/p>\n<ul>\n<li><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/asfau.mp3\" target=\"_blank\">Primeras V\u00edsperas<\/a> (el s\u00e1bado 27 por la tarde)<\/li>\n<li><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/asfaa.mp3\" target=\"_blank\">Laudes<\/a><\/li>\n<li><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/asfav.mp3\" target=\"_blank\">Segundas V\u00edsperas<\/a> <\/li>\n<\/ul>\n<p><strong>Lunes<\/strong>: Navidad, D\u00eda 29 de diciembre<\/p>\n<ul>\n<li><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/n29da.mp3\" target=\"_blank\">Laudes<\/a><\/li>\n<li><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/n29dv.mp3\" target=\"_blank\">V\u00edsperas<\/a><\/li>\n<\/ul>\n<p><strong>Martes<\/strong>: Navidad, D\u00eda 30 de diciembre<\/p>\n<ul>\n<li><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/n30da.mp3\" target=\"_blank\">Laudes<\/a><\/li>\n<li><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/n30dv.mp3\" target=\"_blank\">V\u00edsperas<\/a><\/li>\n<\/ul>\n<p><strong>Mi\u00e9rcoles<\/strong>: Navidad, D\u00eda 31 de diciembre<\/p>\n<ul>\n<li><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/n31da.mp3\" target=\"_blank\">Laudes<\/a><\/li>\n<\/ul>\n<p><strong>Jueves 1 de enero de 2015<\/strong>: <strong>Solemnidad de Santa Mar\u00eda, Madre de Dios<\/strong><\/p>\n<ul>\n<li><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/smamu.mp3\" target=\"_blank\">Primeras V\u00edsperas<\/a> (se rezan el 31 por la tarde)<\/li>\n<li><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/smama.mp3\" target=\"_blank\">Laudes<\/a><\/li>\n<li><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/smamv.mp3\" target=\"_blank\">Segundas V\u00edsperas<\/a><\/li>\n<\/ul>\n<p><strong>Viernes 2 de enero<\/strong>: Memoria de los santos obispos y doctores de la Iglesia Basilio Magno y Gregorio Nazianceno<\/p>\n<ul>\n<li><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/sbyga_s015a.mp3\" target=\"_blank\">Laudes<\/a><\/li>\n<li><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/sbygv_s015v.mp3\" target=\"_blank\">V\u00edsperas<\/a><\/li>\n<\/ul>\n<p><strong>S\u00e1bado<\/strong>: Navidad, D\u00eda 3 de enero<\/p>\n<ul>\n<li><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/n3ena_s016a.mp3\" target=\"_blank\">Laudes<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Domingo 28 de Diciembre: Fiesta de la Sagrada Familia, Ciclo B Primeras V\u00edsperas (el s\u00e1bado 27 por la tarde) Laudes Segundas V\u00edsperas Lunes: Navidad, D\u00eda 29 de diciembre Laudes V\u00edsperas Martes: Navidad, D\u00eda 30 de diciembre Laudes V\u00edsperas Mi\u00e9rcoles: Navidad, D\u00eda 31 de diciembre Laudes Jueves 1 de enero de 2015: Solemnidad de Santa Mar\u00eda, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fraynelson.com\/blog\/2014\/12\/27\/laudes-visperas-para-la-semana-del-28-de-diciembre-de-2014-al-3-de-enero-de-2015\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;Laudes &#038; V\u00edsperas para la semana del 28 de Diciembre de 2014 al 3 de Enero de 2015&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,431],"tags":[],"class_list":["post-32662","post","type-post","status-publish","format-standard","hentry","category-audio","category-liturgia"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/32662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=32662"}],"version-history":[{"count":3,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/32662\/revisions"}],"predecessor-version":[{"id":32665,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/32662\/revisions\/32665"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=32662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=32662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=32662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}