{"id":30577,"date":"2014-09-28T12:27:22","date_gmt":"2014-09-28T17:27:22","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=30577"},"modified":"2014-09-20T15:17:47","modified_gmt":"2014-09-20T20:17:47","slug":"la-gracia-del-martes-30-de-septiembre-de-2014","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2014\/09\/28\/la-gracia-del-martes-30-de-septiembre-de-2014\/","title":{"rendered":"LA GRACIA del Martes 30 de Septiembre de 2014"},"content":{"rendered":"<p>MEMORIA DE SAN JER\u00d3NIMO, PRESB\u00cdTERO Y DOCTOR DE LA IGLESIA<\/p>\n<p>La tarea de la traducci\u00f3n e interpretaci\u00f3n de la Biblia es tarea que ha de renovarse en cada generaci\u00f3n.<\/p>\n<div class=\"powerpress_player\" id=\"powerpress_player_9447\"><audio class=\"wp-audio-shortcode\" id=\"audio-30577-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/fraynelson.com\/homilias_mp3\/20140930.mp3?_=1\" \/><a href=\"http:\/\/fraynelson.com\/homilias_mp3\/20140930.mp3\">http:\/\/fraynelson.com\/homilias_mp3\/20140930.mp3<\/a><\/audio><\/div>\n<p><iframe loading=\"lazy\" title=\"LA GRACIA del Martes 30 de Septiembre de 2014\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/b7P_JoEYbmA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>[REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este archivo de audio en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MEMORIA DE SAN JER\u00d3NIMO, PRESB\u00cdTERO Y DOCTOR DE LA IGLESIA La tarea de la traducci\u00f3n e interpretaci\u00f3n de la Biblia es tarea que ha de renovarse en cada generaci\u00f3n. [REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este archivo de audio en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,297,307,389,841,302],"tags":[],"class_list":["post-30577","post","type-post","status-publish","format-standard","hentry","category-audio","category-biblia","category-homilias","category-interpretacion_de_la_biblia","category-micro-homilias","category-video"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/30577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=30577"}],"version-history":[{"count":2,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/30577\/revisions"}],"predecessor-version":[{"id":30591,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/30577\/revisions\/30591"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=30577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=30577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=30577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}