{"id":29760,"date":"2014-08-22T00:01:52","date_gmt":"2014-08-22T05:01:52","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=29760"},"modified":"2014-08-17T09:38:21","modified_gmt":"2014-08-17T14:38:21","slug":"laudes-20140822","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2014\/08\/22\/laudes-20140822\/","title":{"rendered":"LAUDES 20140822"},"content":{"rendered":"<p>#LaudesFrayNelson para la <strong>Memoria de la Sant\u00edsima Virgen Mar\u00eda, Reina del Universo<\/strong><\/p>\n<div class=\"powerpress_player\" id=\"powerpress_player_5594\"><audio class=\"wp-audio-shortcode\" id=\"audio-29760-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/fraynelson.com\/conferencias\/oracion\/smrea_s045a.mp3?_=1\" \/><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/smrea_s045a.mp3\">http:\/\/fraynelson.com\/conferencias\/oracion\/smrea_s045a.mp3<\/a><\/audio><\/div>\n<p>[REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este camino de oraci\u00f3n en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#LaudesFrayNelson para la Memoria de la Sant\u00edsima Virgen Mar\u00eda, Reina del Universo [REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este camino de oraci\u00f3n en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,1096,413],"tags":[],"class_list":["post-29760","post","type-post","status-publish","format-standard","hentry","category-audio","category-laudes","category-oracion"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/29760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=29760"}],"version-history":[{"count":2,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/29760\/revisions"}],"predecessor-version":[{"id":29779,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/29760\/revisions\/29779"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=29760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=29760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=29760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}