{"id":29644,"date":"2014-08-14T00:02:32","date_gmt":"2014-08-14T05:02:32","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=29644"},"modified":"2014-08-14T01:52:30","modified_gmt":"2014-08-14T06:52:30","slug":"laudes-20140814","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2014\/08\/14\/laudes-20140814\/","title":{"rendered":"LAUDES 20140814"},"content":{"rendered":"<p>#LaudesFrayNelson para la <strong>Memoria de San Maximiliano Ma. Kolbe, presb\u00edtero y m\u00e1rtir<\/strong><\/p>\n<p>[podcast]http:\/\/fraynelson.com\/conferencias\/oracion\/smkoa_s034a.mp3[\/podcast]<\/p>\n<p>[REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este camino de oraci\u00f3n en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#LaudesFrayNelson para la Memoria de San Maximiliano Ma. Kolbe, presb\u00edtero y m\u00e1rtir [podcast]http:\/\/fraynelson.com\/conferencias\/oracion\/smkoa_s034a.mp3[\/podcast] [REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este camino de oraci\u00f3n en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,1096,413],"tags":[],"class_list":["post-29644","post","type-post","status-publish","format-standard","hentry","category-audio","category-laudes","category-oracion"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/29644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=29644"}],"version-history":[{"count":4,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/29644\/revisions"}],"predecessor-version":[{"id":29670,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/29644\/revisions\/29670"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=29644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=29644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=29644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}