{"id":27877,"date":"2014-05-20T00:03:26","date_gmt":"2014-05-20T05:03:26","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=27877"},"modified":"2014-05-19T22:29:15","modified_gmt":"2014-05-20T03:29:15","slug":"laudes-20140520","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2014\/05\/20\/laudes-20140520\/","title":{"rendered":"LAUDES 20140520"},"content":{"rendered":"<p>#LaudesFrayNelson para el <strong>Martes V de Pascua<\/strong><\/p>\n<div class=\"powerpress_player\" id=\"powerpress_player_3994\"><audio class=\"wp-audio-shortcode\" id=\"audio-27877-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/fraynelson.com\/conferencias\/oracion\/p052a.mp3?_=1\" \/><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/p052a.mp3\">http:\/\/fraynelson.com\/conferencias\/oracion\/p052a.mp3<\/a><\/audio><\/div>\n<p>[REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este camino de oraci\u00f3n en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#LaudesFrayNelson para el Martes V de Pascua [REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este camino de oraci\u00f3n en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,1096,413],"tags":[],"class_list":["post-27877","post","type-post","status-publish","format-standard","hentry","category-audio","category-laudes","category-oracion"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/27877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=27877"}],"version-history":[{"count":2,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/27877\/revisions"}],"predecessor-version":[{"id":27882,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/27877\/revisions\/27882"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=27877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=27877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=27877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}