{"id":24724,"date":"2014-01-02T09:27:39","date_gmt":"2014-01-02T14:27:39","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=24724"},"modified":"2014-01-01T23:29:40","modified_gmt":"2014-01-02T04:29:40","slug":"visperas-del-jueves-2-de-enero-de-2014","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2014\/01\/02\/visperas-del-jueves-2-de-enero-de-2014\/","title":{"rendered":"V\u00cdSPERAS del Jueves 2 de Enero de 2014"},"content":{"rendered":"<p>#V\u00edsperasFrayNelson para la <strong>Memoria de los Santos Basilio y Gregorio de Nacianzo, Doctores de la Iglesia<\/strong><\/p>\n<p>[podcast]http:\/\/fraynelson.com\/conferencias\/oracion\/sbsgv.mp3[\/podcast]<\/p>\n<p>[REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este camino de oraci\u00f3n en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#V\u00edsperasFrayNelson para la Memoria de los Santos Basilio y Gregorio de Nacianzo, Doctores de la Iglesia [podcast]http:\/\/fraynelson.com\/conferencias\/oracion\/sbsgv.mp3[\/podcast] [REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este camino de oraci\u00f3n en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,413,1097],"tags":[],"class_list":["post-24724","post","type-post","status-publish","format-standard","hentry","category-audio","category-oracion","category-visperas"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/24724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=24724"}],"version-history":[{"count":3,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/24724\/revisions"}],"predecessor-version":[{"id":24730,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/24724\/revisions\/24730"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=24724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=24724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=24724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}