{"id":24299,"date":"2013-12-18T11:45:30","date_gmt":"2013-12-18T16:45:30","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=24299"},"modified":"2013-12-13T11:59:40","modified_gmt":"2013-12-13T16:59:40","slug":"la-gracia-del-viernes-20-de-diciembre-de-2013","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2013\/12\/18\/la-gracia-del-viernes-20-de-diciembre-de-2013\/","title":{"rendered":"LA GRACIA del Viernes 20 de Diciembre de 2013"},"content":{"rendered":"<p>La verdadera meta de la religi\u00f3n no es un buen comportamiento sino la plena comuni\u00f3n con Dios.<\/p>\n<div class=\"powerpress_player\" id=\"powerpress_player_5660\"><audio class=\"wp-audio-shortcode\" id=\"audio-24299-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/fraynelson.com\/homilias_mp3\/20131220.mp3?_=1\" \/><a href=\"http:\/\/fraynelson.com\/homilias_mp3\/20131220.mp3\">http:\/\/fraynelson.com\/homilias_mp3\/20131220.mp3<\/a><\/audio><\/div>\n<p><iframe loading=\"lazy\" title=\"LA GRACIA del Viernes 20 de Diciembre de 2013\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/WG3tTuKxSoc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>[REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este archivo de audio en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La verdadera meta de la religi\u00f3n no es un buen comportamiento sino la plena comuni\u00f3n con Dios. [REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este archivo de audio en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,345,307,841,325,553,302],"tags":[],"class_list":["post-24299","post","type-post","status-publish","format-standard","hentry","category-audio","category-comunion","category-homilias","category-micro-homilias","category-religiones","category-santidad","category-video"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/24299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=24299"}],"version-history":[{"count":4,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/24299\/revisions"}],"predecessor-version":[{"id":24335,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/24299\/revisions\/24335"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=24299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=24299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=24299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}