{"id":22847,"date":"2013-10-02T10:00:01","date_gmt":"2013-10-02T15:00:01","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=22847"},"modified":"2013-10-02T10:06:13","modified_gmt":"2013-10-02T15:06:13","slug":"visperas-del-miercoles-2-de-octubre-de-2013","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2013\/10\/02\/visperas-del-miercoles-2-de-octubre-de-2013\/","title":{"rendered":"V\u00cdSPERAS del Mi\u00e9rcoles 2 de Octubre de 2013"},"content":{"rendered":"<p>#VisperasFrayNelson correspondientes a la <strong>Memoria de los Santos \u00c1ngeles Custodios<\/strong><\/p>\n<div class=\"powerpress_player\" id=\"powerpress_player_8626\"><audio class=\"wp-audio-shortcode\" id=\"audio-22847-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/fraynelson.com\/conferencias\/oracion\/sacuv.mp3?_=1\" \/><a href=\"http:\/\/fraynelson.com\/conferencias\/oracion\/sacuv.mp3\">http:\/\/fraynelson.com\/conferencias\/oracion\/sacuv.mp3<\/a><\/audio><\/div>\n<p>[REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este camino de oraci\u00f3n en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#VisperasFrayNelson correspondientes a la Memoria de los Santos \u00c1ngeles Custodios [REPRODUCCI\u00d3N PERMITIDA &#8211; Ay\u00fadanos a divulgar este camino de oraci\u00f3n en las redes sociales, blogs, emisoras de radio, y otros medios.]<\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[563,291,413,1097],"tags":[],"class_list":["post-22847","post","type-post","status-publish","format-standard","hentry","category-angeles","category-audio","category-oracion","category-visperas"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/22847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=22847"}],"version-history":[{"count":2,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/22847\/revisions"}],"predecessor-version":[{"id":22878,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/22847\/revisions\/22878"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=22847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=22847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=22847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}