{"id":204,"date":"2005-02-12T01:27:00","date_gmt":"2005-02-12T06:27:00","guid":{"rendered":"566344476"},"modified":"2005-08-25T07:13:11","modified_gmt":"2005-08-25T07:13:11","slug":"531","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2005\/02\/12\/531\/","title":{"rendered":"Con toda la seriedad de un juego (9)"},"content":{"rendered":"<p><strong>La Adrenalina<\/strong><\/p>\n<p>Te\u00f3ricamente los juegos sirven para relajarse pero es un hecho que tensionarse es tambi\u00e9n un modo de jugar.<\/p>\n<p>Claro est\u00e1: no cualquier tensi\u00f3n es un juego. Tener una deuda de dif\u00edcil pago mal puede llamarse una forma de jugar. Sin embargo, una persona endeudada puede querer jugar un agitado partido de squash para descargar en las emociones de ese deporte mucho de la tensi\u00f3n de su vida &#8220;real.&#8221;<\/p>\n<p><!--more--><\/p>\n<p>Otras veces la tensi\u00f3n toma la forma no de un esfuerzo sino de un reto. Lograr algo arduo es un modo de concentrar las facultades y, si se logra lo deseado, levantar la autoestima. Muchos pasatiempos y aficiones parecen ir en esta l\u00ednea. Pienso por ejemplo en la gente que gasta horas de esforzada atenci\u00f3n tratando de hacer un modelo a escala de un barco del siglo XVI. Podemos ver su ce\u00f1o fruncido, las manos crispadas, la frente sudorosa: no es f\u00e1cil lograr que la cubierta del barco quede exactamente en su sitio, y sin embargo, en otro sentido no pasar\u00eda nada si quedara mal, excepto que el reto no habr\u00eda sido superado.<\/p>\n<p>En otras ocasiones a\u00fan, la tensi\u00f3n se hermana con el peligro. Tomar una curva en una pista a m\u00e1s de 200 kil\u00f3metros por hora es eso: sentir un chorro de adrenalina, o a\u00fan m\u00e1s que eso: sentirse vivo, aunque s\u00f3lo sea porque se est\u00e1 venciendo a la muerte. Jugar en este caso se equipara con apelar a las ra\u00edces de la vida, incluyo si ello comporta la posibilidad de perder la vida misma.<\/p>\n<p>No es tan f\u00e1cil hacer una valoraci\u00f3n moral de esa clase de actividades. Supe del caso de un muchacho espa\u00f1ol que muri\u00f3 instant\u00e1neamente porque se revent\u00f3 el cable que lo sosten\u00eda de un puente del cual hab\u00eda saltado seg\u00fan las reglas del &#8220;jumping.&#8221; Uno no puede sino lamentar algo as\u00ed y una muerte semejante s\u00f3lo puede ser llamada absurda. Sin embargo de lo cual, y sin querer hacer de abogados del diablo, \u00bfno es absurdo tambi\u00e9n morir sepultado de papeles en una oficina tratando de mantener aceitados los engranajes de una empresa gigantesca que se alimenta de eso, del trabajo interminable de sus bur\u00f3cratas? No defiendo ninguna muerte sino pido que la vida tenga su sabor y no pierda su color y su aroma. Detr\u00e1s de ese &#8220;sabor&#8221; la gente trata de experimentar toda suerte de cosas, no me cabe duda.<\/p>\n<p>Aunque habr\u00eda otras maneras de acercarse a las fronteras de la muerte con algo m\u00e1s de creatividad y de fruto. Hasta el d\u00eda de hoy ninguna muerte me parece m\u00e1s noble que morir dando vida. No es, no puede ser lo mismo, inmolarse por un poco de adrenalina que sacrificarse hasta el extremo para que otros puedan vivir.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Adrenalina Te\u00f3ricamente los juegos sirven para relajarse pero es un hecho que tensionarse es tambi\u00e9n un modo de jugar. Claro est\u00e1: no cualquier tensi\u00f3n es un juego. Tener una deuda de dif\u00edcil pago mal puede llamarse una forma de jugar. Sin embargo, una persona endeudada puede querer jugar un agitado partido de squash para &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fraynelson.com\/blog\/2005\/02\/12\/531\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;Con toda la seriedad de un juego (9)&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[],"class_list":["post-204","post","type-post","status-publish","format-standard","hentry","category-filosofia-y-psicologia"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=204"}],"version-history":[{"count":0,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/204\/revisions"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}