{"id":16639,"date":"2012-09-20T01:53:16","date_gmt":"2012-09-20T06:53:16","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=16639"},"modified":"2012-09-19T11:03:44","modified_gmt":"2012-09-19T16:03:44","slug":"no-juzgues-antes-de-tiempo","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2012\/09\/20\/no-juzgues-antes-de-tiempo\/","title":{"rendered":"No juzgues antes de tiempo"},"content":{"rendered":"<p>Un m\u00e9dico entr\u00f3 en el hospital de prisa despu\u00e9s de haber sido llamado&#8230; a una cirug\u00eda urgente. \u00c9l contest\u00f3 a la llamada lo antes posible, se cambi\u00f3 de ropa y se fue directamente al bloque de la cirug\u00eda. Encontr\u00f3 el padre del ni\u00f1o ir y venir en la sala de espera para el m\u00e9dico. Una vez al verlo, el padre grit\u00f3: &#8220;\u00bfPor qu\u00e9 tomaste todo este tiempo por venir? \u00bfNo sabes que la vida de mi hijo est\u00e1 en peligro? \u00bfNo tienes sentido de la responsabilidad?&#8221;<\/p>\n<p>El m\u00e9dico sonri\u00f3 y dijo: &#8220;Lo siento, yo no estaba en el hospital y me vine lo m\u00e1s r\u00e1pido que pude despu\u00e9s de recibir la llamada&#8230; Y ahora, me gustar\u00eda que se calme para que yo pueda hacer mi trabajo&#8221;<\/p>\n<p>&#8220;\u00bfQue me calme? \u00bfQu\u00e9 pasar\u00eda si fuera su hijo el que estuviera en esta habitaci\u00f3n ahora mismo? \u00bfEstar\u00edas calmado?&#8221; Si su hijo se estuviera muriendo ahora qu\u00e9 harrias? &#8220;, Dijo el padre enojado<\/p>\n<p>El m\u00e9dico volvi\u00f3 a sonre\u00edr y contest\u00f3: &#8220;Vamos a hacer todo lo posible, con la gracia de Dios.&#8221;<\/p>\n<p>&#8220;Dar consejos cuando no estamos en cuesti\u00f3n es tan f\u00e1cil&#8221;, murmur\u00f3 el padre.<\/p>\n<p>La cirug\u00eda se llev\u00f3 algo m\u00e1s de una angustiosa hora; al final el m\u00e9dico sali\u00f3 feliz: &#8220;\u00a1Gracias a Dios! \u00a1Su hijo se ha salvado!&#8221;<\/p>\n<p>Y sin esperar la respuesta del padre el doctor muy apurado mira su reloj y sale corriendo. Mientras se marchaba le dijo &#8220;Si tiene alguna pregunta, dir\u00edjase a la enfermera.&#8221;<\/p>\n<p>&#8220;\u00bfPor qu\u00e9 el es tan arrogante? No pod\u00eda esperar algunos minutos mas para preguntarle sobre el estado de mi hijo?&#8221;<\/p>\n<p>La enfermera respondi\u00f3, con l\u00e1grimas en su rostro: &#8220;El hijo del doctor muri\u00f3 ayer en un accidente de carretera, y el medico estaba en la funeraria cuando usted le llam\u00f3 para que realizara la cirug\u00eda de su hijo. Ya le salv\u00f3 la vida a su hijo, d\u00e9jelo ir. Se fue corriendo para terminar el entierro de su hijo.&#8221;<\/p>\n<p>&#8211;Nunca juzgues a nadie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un m\u00e9dico entr\u00f3 en el hospital de prisa despu\u00e9s de haber sido llamado&#8230; a una cirug\u00eda urgente. \u00c9l contest\u00f3 a la llamada lo antes posible, se cambi\u00f3 de ropa y se fue directamente al bloque de la cirug\u00eda. Encontr\u00f3 el padre del ni\u00f1o ir y venir en la sala de espera para el m\u00e9dico. Una &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fraynelson.com\/blog\/2012\/09\/20\/no-juzgues-antes-de-tiempo\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;No juzgues antes de tiempo&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[276,64,52],"tags":[],"class_list":["post-16639","post","type-post","status-publish","format-standard","hentry","category-consejos-espirituales","category-relatos-edificantes","category-valores"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/16639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=16639"}],"version-history":[{"count":1,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/16639\/revisions"}],"predecessor-version":[{"id":16640,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/16639\/revisions\/16640"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=16639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=16639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=16639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}