{"id":15078,"date":"2012-05-28T06:47:07","date_gmt":"2012-05-28T11:47:07","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=15078"},"modified":"2012-06-01T13:48:53","modified_gmt":"2012-06-01T18:48:53","slug":"encuentro-con-cristo-y-conversion-a-dios","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2012\/05\/28\/encuentro-con-cristo-y-conversion-a-dios\/","title":{"rendered":"Encuentro con Cristo y conversion a Dios"},"content":{"rendered":"<p><strong>Conferencia para la Cena Cursillista en Pentecost\u00e9s de 2012<\/strong>.<\/p>\n<div class=\"powerpress_player\" id=\"powerpress_player_863\"><audio class=\"wp-audio-shortcode\" id=\"audio-15078-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/fraynelson.com\/conferencias\/discipulos\/encuentro_con_Cristo_y_conversion.mp3?_=1\" \/><a href=\"http:\/\/fraynelson.com\/conferencias\/discipulos\/encuentro_con_Cristo_y_conversion.mp3\">http:\/\/fraynelson.com\/conferencias\/discipulos\/encuentro_con_Cristo_y_conversion.mp3<\/a><\/audio><\/div>\n<p>(1) S\u00f3lo hay encuentro donde hay la altura ontol\u00f3gica propia de la persona; porque todo genuino encuentro implica una forma de donaci\u00f3n.<\/p>\n<p>(2) Los Evangelios cuentan de personas que cambiaron maravillosamente el rumbo de su vida por un encuentro con Cristo; pero no es el caso de todos. \u00bfQu\u00e9 fall\u00f3? El Se\u00f1or nos recuerda que nadie llega a \u00e9l si el Padre no lo atrae. Esta expresi\u00f3n nos invita a confiar en la hora de Dios para cada persona pero adem\u00e1s nos llama a reconocer que en lo que somos como creaturas est\u00e1 un llamado profundo a ir hacia Cristo. Tanto nuestras fortalezas como nuestras debilidades miran hacia \u00e9l. Y por cierto: si pretendemos apoyarnos s\u00f3lo en lo que vemos fuerte en nosotros, es ah\u00ed cuando no hay encuentro sino desencuentro con Cristo.<\/p>\n<p>(3) Cristo no quiere un encuentro superficial o pasajero con nosotros. Su lenguaje es el de la donaci\u00f3n total, como se manifiesta y realiza en la Eucarist\u00eda. El encuentro ha de crecer hasta llegara ser &#8220;permanencia.&#8221; Cristo llega vivo a nosotros, y la vida cristiana no es simple esfuerzo de adecuarse a un modelo maravilloso, sino que es el fruto natural que irradia Cristo viviendo en nosotros sus propios misterios.<\/p>\n<p>(4) Evangelizar es ofrecer este Cristo a nuestros hermanos. Encontraremos rechazo, porque el pecado va creando redes de complicidad, que la Biblia llama &#8220;mundo.&#8221; Hay que tener en cuenta que: (a) Habr\u00e1 confrontaci\u00f3n, y que todos tendremos una cuota de martirio. (b) Es preciso que los laicos comprendan el valor y la necesidad de asociarse para defender p\u00fablicamente su fe. (c) Hay que orar siempre m\u00e1s y siempre mejor.<\/p>\n<p><iframe loading=\"lazy\" width=\"420\" height=\"315\" src=\"http:\/\/www.youtube.com\/embed\/cGCfUuaFHlk\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conferencia para la Cena Cursillista en Pentecost\u00e9s de 2012. (1) S\u00f3lo hay encuentro donde hay la altura ontol\u00f3gica propia de la persona; porque todo genuino encuentro implica una forma de donaci\u00f3n. (2) Los Evangelios cuentan de personas que cambiaron maravillosamente el rumbo de su vida por un encuentro con Cristo; pero no es el caso &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fraynelson.com\/blog\/2012\/05\/28\/encuentro-con-cristo-y-conversion-a-dios\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;Encuentro con Cristo y conversion a Dios&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,322,317,302],"tags":[],"class_list":["post-15078","post","type-post","status-publish","format-standard","hentry","category-audio","category-conversion","category-jesucristo","category-video"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/15078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=15078"}],"version-history":[{"count":5,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/15078\/revisions"}],"predecessor-version":[{"id":15134,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/15078\/revisions\/15134"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=15078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=15078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=15078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}