{"id":14839,"date":"2012-05-08T02:39:28","date_gmt":"2012-05-08T07:39:28","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=14839"},"modified":"2012-05-08T08:12:47","modified_gmt":"2012-05-08T13:12:47","slug":"catequesis-sobre-la-alegria","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2012\/05\/08\/catequesis-sobre-la-alegria\/","title":{"rendered":"ESCUCHA, Catequesis sobre la Alegria"},"content":{"rendered":"<p>* En medio de tribulaciones, el papa Pablo VI escribi\u00f3 su carta sobre la Alegr\u00eda Cristiana. Por extra\u00f1o que parezca no es del todo excepcional: la Cruz y la Alegr\u00eda es tema en un n\u00famero considerable de vidas de santos.<\/p>\n<p>* En Juan 16, Jes\u00fas muestra que hay tres tipos de alegr\u00eda: (1) Una que es buena pero inmadura e incompleta, y que sucumbe a la hora de la prueba. Corresponde al entusiasmo del reci\u00e9n convertido. (2) La alegr\u00eda mundana, autoafirmaci\u00f3n del &#8220;yo,&#8221; y que nos persigue aunque nos creamos buenos. (3) La verdadera alegr\u00eda, que cumple tres condiciones: (a) Asume lo peor desde el deseo de no separarse de Dios ni quitarle el primer lugar; (b) Recibe la visita de Cristo y quiere permanecer con \u00e9l y en \u00e9l. (c) Da testimonio, no como quien impone su verdad, sino como quien esparce la semilla y se alegra de que crezca en alguna parte.<\/p>\n<div class=\"powerpress_player\" id=\"powerpress_player_9931\"><audio class=\"wp-audio-shortcode\" id=\"audio-14839-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/fraynelson.com\/conferencias\/discipulos\/catequesis_sobre_la_alegria.mp3?_=1\" \/><a href=\"http:\/\/fraynelson.com\/conferencias\/discipulos\/catequesis_sobre_la_alegria.mp3\">http:\/\/fraynelson.com\/conferencias\/discipulos\/catequesis_sobre_la_alegria.mp3<\/a><\/audio><\/div>\n","protected":false},"excerpt":{"rendered":"<p>* En medio de tribulaciones, el papa Pablo VI escribi\u00f3 su carta sobre la Alegr\u00eda Cristiana. Por extra\u00f1o que parezca no es del todo excepcional: la Cruz y la Alegr\u00eda es tema en un n\u00famero considerable de vidas de santos. * En Juan 16, Jes\u00fas muestra que hay tres tipos de alegr\u00eda: (1) Una que &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fraynelson.com\/blog\/2012\/05\/08\/catequesis-sobre-la-alegria\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;ESCUCHA, Catequesis sobre la Alegria&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[650,291,962],"tags":[],"class_list":["post-14839","post","type-post","status-publish","format-standard","hentry","category-alegria","category-audio","category-pablo-vi"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/14839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=14839"}],"version-history":[{"count":2,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/14839\/revisions"}],"predecessor-version":[{"id":14841,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/14839\/revisions\/14841"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=14839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=14839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=14839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}