{"id":14391,"date":"2012-04-05T14:07:20","date_gmt":"2012-04-05T19:07:20","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=14391"},"modified":"2012-04-05T14:07:20","modified_gmt":"2012-04-05T19:07:20","slug":"amor-humano-y-amor-divino-2-de-3","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2012\/04\/05\/amor-humano-y-amor-divino-2-de-3\/","title":{"rendered":"Amor Humano y Amor Divino, 2 de 3"},"content":{"rendered":"<p>Retiro abierto en la ciudad de Santa Cruz (Bolivia), con motivo de la Semana Santa 2012. Tema 2: Amor de pareja.<\/p>\n<p>* Nuestro tiempo sufre de dura soledad existencial, que es p\u00e9sima consejera, y que adem\u00e1s favorece toda clase de experimentos afectivos, sin excluir variaciones en torno al matrimonio. No es buen ambiente para comprender la belleza y el lugar que ocupa el plan de pareja en el plan de Dios.<\/p>\n<p>* La mujer es &#8220;ministra de la vida.&#8221; No podemos definir con claridad qu\u00e9 ser\u00e1 el futuro de la humanidad pero s\u00ed sabemos que ese futuro saldr\u00e1 del vientre de la mujer.<\/p>\n<p>* Provista por Dios, la mujer tiene lo m\u00e1s necesario para la vida naciente. De ah\u00ed su capacidad de atenci\u00f3n a m\u00faltiples frentes a la vez (pensamiento paralelo), su destreza en producir y leer el lenguaje emocional, su percepci\u00f3n m\u00faltiple y sincr\u00f3nica de la s relaciones interpersonales.<\/p>\n<p>* El var\u00f3n, en cambio, tiene de atener una atenci\u00f3n m\u00e1s focal. Su ritmo propio al enamorarse es &#8220;resolver un problema.&#8221; La mujer, en cambio, desea encontrar la ruta que har\u00e1 que su generosidad y donaci\u00f3n encuentren cauce.<\/p>\n<p>* Si el var\u00f3n busca &#8220;casa&#8221; en la mujer; \u00e9sta busca qui\u00e9n es admirable respetuoso y a la vez atento a ella. S\u00f3lo cuando los ritmos de ellos se encuentran y complementan es posible una relaci\u00f3n arm\u00f3nica seg\u00fan el plan de Dios.<\/p>\n<p>+ Ese plan divino se expresa perfectamente en las bodas de Cristo con su Iglesia.<\/p>\n<div class=\"powerpress_player\" id=\"powerpress_player_5318\"><audio class=\"wp-audio-shortcode\" id=\"audio-14391-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/fraynelson.com\/conferencias\/discipulos\/amor_humano_y_divino_2_de_3.mp3?_=1\" \/><a href=\"http:\/\/fraynelson.com\/conferencias\/discipulos\/amor_humano_y_divino_2_de_3.mp3\">http:\/\/fraynelson.com\/conferencias\/discipulos\/amor_humano_y_divino_2_de_3.mp3<\/a><\/audio><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Retiro abierto en la ciudad de Santa Cruz (Bolivia), con motivo de la Semana Santa 2012. Tema 2: Amor de pareja. * Nuestro tiempo sufre de dura soledad existencial, que es p\u00e9sima consejera, y que adem\u00e1s favorece toda clase de experimentos afectivos, sin excluir variaciones en torno al matrimonio. No es buen ambiente para comprender &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fraynelson.com\/blog\/2012\/04\/05\/amor-humano-y-amor-divino-2-de-3\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;Amor Humano y Amor Divino, 2 de 3&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[405,948,291,606,408,453],"tags":[],"class_list":["post-14391","post","type-post","status-publish","format-standard","hentry","category-amor","category-amor-humano-y-amor-divino","category-audio","category-bolivia","category-hombres_y_mujeres","category-pareja"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/14391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=14391"}],"version-history":[{"count":1,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/14391\/revisions"}],"predecessor-version":[{"id":14393,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/14391\/revisions\/14393"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=14391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=14391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=14391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}