{"id":13542,"date":"2012-02-08T01:38:07","date_gmt":"2012-02-08T06:38:07","guid":{"rendered":"http:\/\/fraynelson.com\/blog\/?p=13542"},"modified":"2012-02-04T15:22:02","modified_gmt":"2012-02-04T20:22:02","slug":"150-powerpoints-para-los-150-salmos","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2012\/02\/08\/150-powerpoints-para-los-150-salmos\/","title":{"rendered":"150 powerpoints para los 150 salmos"},"content":{"rendered":"<p>&#8220;Por fin veo cumplido un deseo, desde hace tiempo so\u00f1ado: elaborar 150 presentaciones (PPS) con los salmos de la Biblia, utilizando la traducci\u00f3n oficial de la Liturgia de las Horas. \u201cOrar con los Salmos\u201d, es mi peque\u00f1a colaboraci\u00f3n para compartir,  en medio de tanta y tan cargada informaci\u00f3n de internet, un espacio para la escucha, la alabanza y la plegaria. En los salmos est\u00e1n grabadas las experiencias de fe del pueblo de Dios, del mismo Jesucristo, de toda la Iglesia, que aclaman, cantan, agradecen, suplican, buscan y anhelan la fidelidad al Se\u00f1or y el encuentro con \u00c9l.  Experiencias que son tambi\u00e9n las nuestras porque somos \u201cpueblo\u201d y reba\u00f1o\u201d del \u00fanico Dios. (Sal. 99, v. 3) La fuerza est\u00e1 en la Palabra; deseo que la imagen la acompa\u00f1e y arrope para que facilite \u201corar con los salmos\u201d&#8230;&#8221;<\/p>\n<p><a href=\"http:\/\/www.auladereli.es\/los-150-salmos-en-power-point.html\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/fraynelson.com\/banco_imagenes\/recomendados\/20120210.jpg\" alt=\"150 powerpoints 150 salmos\" \/><\/p>\n<p>Click!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Por fin veo cumplido un deseo, desde hace tiempo so\u00f1ado: elaborar 150 presentaciones (PPS) con los salmos de la Biblia, utilizando la traducci\u00f3n oficial de la Liturgia de las Horas. \u201cOrar con los Salmos\u201d, es mi peque\u00f1a colaboraci\u00f3n para compartir, en medio de tanta y tan cargada informaci\u00f3n de internet, un espacio para la escucha, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fraynelson.com\/blog\/2012\/02\/08\/150-powerpoints-para-los-150-salmos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;150 powerpoints para los 150 salmos&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[620,413,329],"tags":[],"class_list":["post-13542","post","type-post","status-publish","format-standard","hentry","category-enlaces","category-oracion","category-salmos"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/13542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=13542"}],"version-history":[{"count":2,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/13542\/revisions"}],"predecessor-version":[{"id":13551,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/13542\/revisions\/13551"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=13542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=13542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=13542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}