{"id":1180,"date":"2004-10-17T14:21:40","date_gmt":"2004-10-17T19:21:40","guid":{"rendered":"1374249484"},"modified":"2005-10-17T18:25:52","modified_gmt":"2005-10-17T18:25:52","slug":"liberado_del_sola_scriptura","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2004\/10\/17\/liberado_del_sola_scriptura\/","title":{"rendered":"Liberado del &#8220;Sola Scriptura&#8221;"},"content":{"rendered":"<p>Transcribo a continuaci\u00f3n un interesante testimonio sobre los problemas de Sola Scriptura, narrados por un profesor y te\u00f3logo protestante: Scott Hahn.<\/p>\n<p><p>En mi clase de Historia de la Iglesia, uno de mis mejores alumnos (antiguo cat\u00f3lico) expuso un trabajo sobre el Concilio de Trento, y al terminar me hizo una embarazosa pregunta que yo nunca hab\u00eda escuchado. Dijo:<\/p>\n<p><p>&#8211; Profesor Hahn, usted nos ha ense\u00f1ado que la doctrina de Sola Fide no es b\u00edblica, y que ese grito de guerra de la Reforma no tiene ning\u00fan fundamento si se confronta con la interpretaci\u00f3n de Pablo. Como usted bien sabe, el otro grito de guerra de la Reforma Protestante fue Sola Scriptura: que la Biblia es nuestra \u00fanica autoridad, en lugar del Papa, los Concilios o la Tradici\u00f3n. Profesor: \u00bfd\u00f3nde ense\u00f1a la Biblia que la Escritura es nuestra \u00fanica autoridad?<\/p>\n<p><p>Me le qued\u00e9 mirando y empec\u00e9 a sentir un sudor fr\u00edo.<\/p>\n<p><p>En el seminario yo ten\u00eda fama de ser una avispa socr\u00e1tica, que siempre pon\u00eda en aprietos a otros con inc\u00f3modas preguntas; pero \u00e9sta nunca se me hab\u00eda ocurrido.<\/p>\n<p><p>Respond\u00ed lo que cualquier profesor al que han pillado desprevenido hubiera contestado: &#8220;\u00a1Qu\u00e9 pregunta m\u00e1s tonta!&#8221;. Pero en cuanto esas palabras salieron de mi boca me sent\u00ed derrotado, pues me hab\u00eda prometido que como docente jam\u00e1s usar\u00eda esa expresi\u00f3n.<\/p>\n<p><p>El alumno no se acobard\u00f3. El sab\u00eda que no era una pregunta tonta, as\u00ed que mir\u00e1ndome directamente a los ojos, me ret\u00f3:<\/p>\n<p><p>-Bien, pues entonces d\u00e9me al menos una respuesta tonta.<\/p>\n<p><p>Le dije:<\/p>\n<p><p>&#8211; Vayamos primero a Mateo 5, 17 y luego veamos 2 Tim 3: 16-17: &#8220;Toda Escritura inspirada por Dios es \u00fatil para ense\u00f1ar, para rebatir, para corregir y para formar en la justicia, de modo que el hombre de Dios sea perfecto, y preparado para toda obra buena&#8221; Y luego podemos ver tambi\u00e9n qu\u00e9 dice Jes\u00fas acerca de la Tradici\u00f3n en Mateo 15.<\/p>\n<p><p>Su respuesta fue cortante:<\/p>\n<p><p>&#8211; Pero profesor, Jes\u00fas no estaba condenando toda tradici\u00f3n en Mateo 15, sino s\u00f3lo las tradiciones corruptas. Cuando 2 Tim 3, 16 menciona &#8220;Toda la Escritura&#8221; no dice &#8220;solo la Escritura&#8221; es \u00fatil. Tambi\u00e9n la oraci\u00f3n, la evangelizaci\u00f3n y otras muchas cosas son esenciales. \u00bfY qu\u00e9 decir de 2 Tes 2:15?<\/p>\n<p><p>&#8211; Oh, s\u00ed&#8230; Tesalonicenses&#8230;.-musit\u00e9 d\u00e9bilmente-, \u00bfqu\u00e9 dice ah\u00ed?<\/p>\n<p><p>-Pablo dice a los tesalonicenses: &#8220;Por lo tanto, hermanos, manteneos firmes y guardad las tradiciones que hab\u00e9is aprendido de nosotros, de palabra o por carta&#8221;.<\/p>\n<p><p>Me sal\u00ed por la tangente:<\/p>\n<p><p>-\u00bfSabes John?, nos estamos alejando del tema. Avancemos un poco m\u00e1s y ya hablaremos algo sobre esto la pr\u00f3xima semana.<\/p>\n<p><p>Puedo asegurar que \u00e9l no qued\u00f3 satisfecho. Y yo tampoco.<\/p>\n<p><p>Mientras volv\u00eda a casa aquella noche, mir\u00e9 las estrellas y murmur\u00e9: Se\u00f1or, qu\u00e9 est\u00e1 pasando? \u00bfD\u00f3nde ense\u00f1a la Escritura Sola Scriptura?<\/p>\n<p><p>Eran dos las columnas sobre las que los protestantes basaban su revoluci\u00f3n contra Roma. Una ya hab\u00eda ca\u00eddo, y la otra se estaba tambaleando. Sent\u00ed miedo.<\/p>\n<p><p>Estudi\u00e9 durante toda la semana sin llegar a ninguna conclusi\u00f3n. Llam\u00e9 incluso a varios amigos, pero no hice ning\u00fan progreso. Finalmente habl\u00e9 con dos de los mejores te\u00f3logos de Am\u00e9rica, y tambi\u00e9n con algunos de mis ex profesores. Todos aquellos a los que consultaba se sorprend\u00edan de que yo les hiciera esa pregunta, y se sent\u00edan a\u00fan m\u00e1s trastornados cuando yo no quedaba satisfecho con sus respuestas. A un profesor le dije:<\/p>\n<p><p>-Tal vez sufro de amnesia, pero he olvidado las simples razones por las que los protestantes creemos que la Biblia es nuestra \u00fanica autoridad.<\/p>\n<p><p>-Scott, que pregunta tan tonta.<\/p>\n<p><p>-Pues d\u00e9me una respuesta tonta.<\/p>\n<p><p>-Scott &#8211;replic\u00f3-, en realidad t\u00fa no puedes explicar la doctrina de Sola Scriptura con la Escritura. La b\u00edblia no ense\u00f1a expl\u00edcitamente que ella sea la \u00fanica autoridad para los cristianos. En otras palabras, Scott, Sola Scriptura es en esencia la creencia hist\u00f3rica de los reformadores, frente a la pretensi\u00f3n cat\u00f3lica de que la autoridad est\u00e1 en la Escritura y adem\u00e1s, en la Iglesia y la Tradici\u00f3n. Para nosotros, por tanto, \u00e9sta es s\u00f3lo una presuposici\u00f3n teol\u00f3gica, nuestro punto de partida, m\u00e1s que una conclusi\u00f3n demostrada.<\/p>\n<p><p>Despu\u00e9s me ofreci\u00f3 los mismos textos de la Escritura que yo le hab\u00eda indicado a mi alumno, y yo le di las mismas agudas respuestas<\/p>\n<p><p>-\u00bfQu\u00e9 m\u00e1s podr\u00edamos a\u00f1adir?- le dije.<\/p>\n<p><p>-Scott, mira lo que ense\u00f1a la Iglesia cat\u00f3lica. Es obvio que la Tradici\u00f3n est\u00e1 equivocada.<\/p>\n<p><p>-Obviamente est\u00e1 equivicada- asent\u00ed-. Pero \u00bfd\u00f3nde se condena el concepto de Tradici\u00f3n? Y por otro lado, \u00bfqu\u00e9 quiso decir Pablo cuando ped\u00eda a los Tesalonicenses que se ajustaran a la Tradici\u00f3n tanto escrita como oral? &#8211; segu\u00ed apasionado-. \u00bfNo es ir\u00f3nico? Nosotros insistimos en que los cristianos s\u00f3lo pueden creer lo que la Biblia ense\u00f1a, pero la propia Biblia no ense\u00f1a que ella sea nuestra \u00fanica autoridad.<\/p>\n<p><p>Le pregunt\u00e9 a otro te\u00f3logo:<\/p>\n<p><p>-\u00bfCu\u00e1les para ti el pilar y fundamento de la verdad?<\/p>\n<p><p>-La Biblia, por supuesto.<\/p>\n<p><p>-Entonces \u00bfpor qu\u00e9 la Biblia dice en 1 Tim 3:15 que la Iglesia es el pilar y el fundamento de la verdad?<\/p>\n<p><p>-\u00a1T\u00fa me trastornas, Scott!<\/p>\n<p><p>-\u00a1Soy yo quien se siente trastornado!<\/p>\n<p><p>-Pero Scott, \u00bfqu\u00e9 Iglesia&#8230;?<\/p>\n<p><p>-\u00bfCu\u00e1ntos candidatos para el puesto hay ah\u00ed&#8230;? Quiero decir: \u00bfcu\u00e1ntas iglesias dicen ser la columna y fundamento de la verdad?<\/p>\n<p><p>-\u00bfQuiere decir esto que te est\u00e1s convirtiendo al catolicismo?<\/p>\n<p><p>-Espero que no&#8230;.<\/p>\n<p><p>Hasta aqu\u00ed el texto. Finalmente Scott Hahn se convirti\u00f3 a la fe cat\u00f3lica junto a su esposa, tambi\u00e9n te\u00f3loga protestante. El texto es sacado del libro Rome Sweet Home, de Scott y Kimberly Hahn.<\/p>\n<p>\n","protected":false},"excerpt":{"rendered":"<p>Transcribo a continuaci\u00f3n un interesante testimonio sobre los problemas de Sola Scriptura, narrados por un profesor y te\u00f3logo protestante: Scott Hahn. En mi clase de Historia de la Iglesia, uno de mis mejores alumnos (antiguo cat\u00f3lico) expuso un trabajo sobre el Concilio de Trento, y al terminar me hizo una embarazosa pregunta que yo nunca &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/fraynelson.com\/blog\/2004\/10\/17\/liberado_del_sola_scriptura\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;Liberado del &#8220;Sola Scriptura&#8221;&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1138,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[],"class_list":["post-1180","post","type-post","status-publish","format-standard","hentry","category-testimonios"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/1180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1138"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=1180"}],"version-history":[{"count":0,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/1180\/revisions"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=1180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=1180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=1180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}