{"id":117183,"date":"2026-03-31T16:01:58","date_gmt":"2026-03-31T21:01:58","guid":{"rendered":"https:\/\/fraynelson.com\/blog\/?p=117183"},"modified":"2026-03-24T14:23:35","modified_gmt":"2026-03-24T19:23:35","slug":"rosario-de-las-semanas-2026-04-01","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2026\/03\/31\/rosario-de-las-semanas-2026-04-01\/","title":{"rendered":"ROSARIO de las Semanas 2026\/04\/01"},"content":{"rendered":"<p><div class=\"powerpress_player\" id=\"powerpress_player_6778\"><audio class=\"wp-audio-shortcode\" id=\"audio-117183-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa03.mp3?_=1\" \/><a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa03.mp3\">http:\/\/traffic.libsyn.com\/fraynelson\/rosa03.mp3<\/a><\/audio><\/div><p class=\"powerpress_links powerpress_links_mp3\" style=\"margin-bottom: 1px !important;\">Podcast: <a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa03.mp3\" class=\"powerpress_link_pinw\" target=\"_blank\" title=\"Play in new window\" onclick=\"return powerpress_pinw('https:\/\/fraynelson.com\/blog\/?powerpress_pinw=117183-podcast');\" rel=\"nofollow\">Play in new window<\/a> | <a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa03.mp3\" class=\"powerpress_link_d\" title=\"Download\" rel=\"nofollow\" download=\"rosa03.mp3\">Download<\/a><\/p><p class=\"powerpress_links powerpress_subscribe_links\">Subscribe: <a href=\"https:\/\/fraynelson.com\/blog\/feed\/podcast\/\" class=\"powerpress_link_subscribe powerpress_link_subscribe_rss\" target=\"_blank\" title=\"Subscribe via RSS\" rel=\"nofollow\">RSS<\/a><\/p>#RosarioFrayNelson para el <strong>Mi\u00e9rcoles<\/strong>:<br \/>\nContemplamos los <em>Misterios de la Infancia de Jes\u00fas<\/em><br \/>\n<iframe loading=\"lazy\" title=\"Rosario de las Semanas - Para los d\u00edas MI\u00c9RCOLES\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/iNaUDy36-0w?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><br \/>\nUsamos <a href=\"http:\/\/fraynelson.com\/oraciones.html\" target=\"_blank\" rel=\"noopener noreferrer\">esta versi\u00f3n de las oraciones<\/a>.<\/p>\n<ol>\n<li>En el primer misterio de la infancia contemplamos <em>la Anunciaci\u00f3n a Mar\u00eda Sant\u00edsima y la Encarnaci\u00f3n del Hijo de Dios<\/em>.<\/li>\n<li>En el segundo misterio de la infancia contemplamos <em>la visita de la Virgen Madre a su pariente Isabel<\/em>.<\/li>\n<li>En el tercer misterio de la infancia contemplamos <em>el sufrimiento que pas\u00f3 San Jos\u00e9, y la fe amorosa que tuvo<\/em>.<\/li>\n<li>En el cuarto misterio de la infancia contemplamos <em>el Nacimiento del Hijo de Dios en el humilde portal de Bel\u00e9n<\/em>.<\/li>\n<li>En el quinto misterio de la infancia contemplamos <em>la Epifan\u00eda: Jes\u00fas es luz para las naciones, y as\u00ed es adorado por unos magos venidos de Oriente<\/em>.<\/li>\n<li>En el sexto misterio de la infancia contemplamos <em>la Presentaci\u00f3n del Ni\u00f1o Jes\u00fas en el templo de Jerusal\u00e9n<\/em>.<\/li>\n<li>En el s\u00e9ptimo misterio de la infancia contemplamos a <em>Jes\u00fas Ni\u00f1o en el templo, ocupado de las cosas de su Padre del Cielo<\/em>.<\/li>\n<\/ol>\n<p>[<strong>REPRODUCCI\u00d3N PERMITIDA<\/strong> \u2013 Este es un ejercicio privado de devoci\u00f3n &#8220;<em>ad experimentum<\/em>&#8221; en proceso de aprobaci\u00f3n oficial. Puede divulgarse en las redes sociales, blogs, emisoras de radio, y otros medios siempre que al mismo tiempo se haga la presente advertencia.]<\/p>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1140,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,1265],"tags":[],"class_list":["post-117183","post","type-post","status-publish","format-standard","hentry","category-audio","category-rosario-de-las-semanas"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/117183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1140"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=117183"}],"version-history":[{"count":1,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/117183\/revisions"}],"predecessor-version":[{"id":117190,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/117183\/revisions\/117190"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=117183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=117183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=117183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}