{"id":116652,"date":"2026-02-19T16:01:03","date_gmt":"2026-02-19T21:01:03","guid":{"rendered":"https:\/\/fraynelson.com\/blog\/?p=116652"},"modified":"2026-02-11T13:00:59","modified_gmt":"2026-02-11T18:00:59","slug":"rosario-de-las-semanas-2026-02-20","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2026\/02\/19\/rosario-de-las-semanas-2026-02-20\/","title":{"rendered":"ROSARIO de las Semanas 2026\/02\/20"},"content":{"rendered":"<ul>\n<p><div class=\"powerpress_player\" id=\"powerpress_player_3759\"><audio class=\"wp-audio-shortcode\" id=\"audio-116652-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa05.mp3?_=1\" \/><a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa05.mp3\">http:\/\/traffic.libsyn.com\/fraynelson\/rosa05.mp3<\/a><\/audio><\/div><p class=\"powerpress_links powerpress_links_mp3\" style=\"margin-bottom: 1px !important;\">Podcast: <a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa05.mp3\" class=\"powerpress_link_pinw\" target=\"_blank\" title=\"Play in new window\" onclick=\"return powerpress_pinw('https:\/\/fraynelson.com\/blog\/?powerpress_pinw=116652-podcast');\" rel=\"nofollow\">Play in new window<\/a> | <a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa05.mp3\" class=\"powerpress_link_d\" title=\"Download\" rel=\"nofollow\" download=\"rosa05.mp3\">Download<\/a><\/p><p class=\"powerpress_links powerpress_subscribe_links\">Subscribe: <a href=\"https:\/\/fraynelson.com\/blog\/feed\/podcast\/\" class=\"powerpress_link_subscribe powerpress_link_subscribe_rss\" target=\"_blank\" title=\"Subscribe via RSS\" rel=\"nofollow\">RSS<\/a><\/p>#RosarioFrayNelson para el <strong>Viernes<\/strong>:<br \/>\nContemplamos los <em>Misterios de la Dolorosa Pasi\u00f3n<\/em><br \/>\n<iframe loading=\"lazy\" title=\"Rosario de las Semanas - Para los d\u00edas VIERNES\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/avEhozJTsrw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><br \/>\nUsamos <a href=\"http:\/\/fraynelson.com\/oraciones.html\" target=\"_blank\" rel=\"noopener noreferrer\">esta versi\u00f3n de las oraciones<\/a>.<\/p>\n<ol>\n<li>En el primer misterio de la Dolorosa Pasi\u00f3n contemplamos a <em>Jes\u00fas, que vino a los suyos, y los suyos no lo recibieron<\/em>.<\/li>\n<li>En el segundo misterio de la Dolorosa Pasi\u00f3n contemplamos <em>la agon\u00eda de Jes\u00fas en el huerto de Getseman\u00ed intercediendo por nosotros los pecadores<\/em>.<\/li>\n<li>En el tercer misterio de la Dolorosa Pasi\u00f3n contemplamos a <em>Jes\u00fas, juzgado por el sanedr\u00edn, y luego por la autoridad romana, y as\u00ed condenado a muerte<\/em>.<\/li>\n<li>En el cuarto misterio de la Dolorosa Pasi\u00f3n contemplamos <em>la flagelaci\u00f3n de Nuestro Se\u00f1or Jesucristo, porque sus heridas nos han curado<\/em>.<\/li>\n<li>En el quinto misterio de la Dolorosa Pasi\u00f3n contemplamos a <em>Jes\u00fas coronado de espinas: Rey humilde y Pr\u00edncipe de Paz<\/em>.<\/li>\n<li>En el sexto misterio de la Dolorosa Pasi\u00f3n contemplamos a <em>Jes\u00fas que carga con su cruz<\/em>.<\/li>\n<li>En el s\u00e9ptimo misterio de la Dolorosa Pasi\u00f3n contemplamos a <em>Jes\u00fas que muere en la Cruz<\/em>.<\/li>\n<\/ol>\n<p>[<strong>REPRODUCCI\u00d3N PERMITIDA<\/strong> \u2013 Este es un ejercicio privado de devoci\u00f3n &#8220;<em>ad experimentum<\/em>&#8221; en proceso de aprobaci\u00f3n oficial. Puede divulgarse en las redes sociales, blogs, emisoras de radio, y otros medios siempre que al mismo tiempo se haga la presente advertencia.]<\/p>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1140,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,1265],"tags":[],"class_list":["post-116652","post","type-post","status-publish","format-standard","hentry","category-audio","category-rosario-de-las-semanas"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/116652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1140"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=116652"}],"version-history":[{"count":1,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/116652\/revisions"}],"predecessor-version":[{"id":116663,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/116652\/revisions\/116663"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=116652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=116652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=116652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}