{"id":115123,"date":"2025-11-08T16:01:07","date_gmt":"2025-11-08T21:01:07","guid":{"rendered":"https:\/\/fraynelson.com\/blog\/?p=115123"},"modified":"2025-10-27T13:39:53","modified_gmt":"2025-10-27T18:39:53","slug":"rosario-de-las-semanas-2025-11-09","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2025\/11\/08\/rosario-de-las-semanas-2025-11-09\/","title":{"rendered":"ROSARIO de las Semanas 2025\/11\/09"},"content":{"rendered":"<p><div class=\"powerpress_player\" id=\"powerpress_player_6761\"><audio class=\"wp-audio-shortcode\" id=\"audio-115123-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa07.mp3?_=1\" \/><a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa07.mp3\">http:\/\/traffic.libsyn.com\/fraynelson\/rosa07.mp3<\/a><\/audio><\/div><p class=\"powerpress_links powerpress_links_mp3\" style=\"margin-bottom: 1px !important;\">Podcast: <a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa07.mp3\" class=\"powerpress_link_pinw\" target=\"_blank\" title=\"Play in new window\" onclick=\"return powerpress_pinw('https:\/\/fraynelson.com\/blog\/?powerpress_pinw=115123-podcast');\" rel=\"nofollow\">Play in new window<\/a> | <a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/rosa07.mp3\" class=\"powerpress_link_d\" title=\"Download\" rel=\"nofollow\" download=\"rosa07.mp3\">Download<\/a><\/p><p class=\"powerpress_links powerpress_subscribe_links\">Subscribe: <a href=\"https:\/\/fraynelson.com\/blog\/feed\/podcast\/\" class=\"powerpress_link_subscribe powerpress_link_subscribe_rss\" target=\"_blank\" title=\"Subscribe via RSS\" rel=\"nofollow\">RSS<\/a><\/p>#RosarioFrayNelson para el <strong>Domingo<\/strong>:<br \/>\nContemplamos los <em>Misterios de la Gloria del Se\u00f1or<\/em><br \/>\n<iframe loading=\"lazy\" title=\"Rosario de las Semanas - Para los d\u00edas DOMINGOS\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/ez8VQMk9RDY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><br \/>\nUsamos <a href=\"http:\/\/fraynelson.com\/oraciones.html\" target=\"_blank\" rel=\"noopener noreferrer\">esta versi\u00f3n de las oraciones<\/a>.<\/p>\n<ol>\n<li>En el primer misterio glorioso contemplamos <em>la Resurrecci\u00f3n de Nuestro Se\u00f1or Jesucristo<\/em>.<\/li>\n<li>En el segundo misterio glorioso contemplamos <em>la Ascensi\u00f3n de Cristo a los Cielos<\/em>.<\/li>\n<li>En el tercer misterio glorioso contemplamos <em>el d\u00eda de Pentecost\u00e9s: la efusi\u00f3n del Esp\u00edritu Santo da nacimiento a la Iglesia<\/em>.<\/li>\n<li>En el cuarto misterio glorioso contemplamos <em>la santidad de la Iglesia, especialmente visible en sus m\u00e1rtires, ya desde los primeros tiempos<\/em>.<\/li>\n<li>En el quinto misterio glorioso contemplamos <em>la Asunci\u00f3n de la Virgen Mar\u00eda y el poder singular de su intercesi\u00f3n por la Iglesia que peregrina<\/em>.<\/li>\n<li>En el sexto misterio glorioso contemplamos <em>la segunda venida de Cristo, y que de su Reinado han de participar para siempre la Virgen Mar\u00eda y todos los santos<\/em>.<\/li>\n<li>En el s\u00e9ptimo misterio glorioso contemplamos que <em>la muerte misma morir\u00e1, y que Dios ser\u00e1 todo en todos<\/em>.<\/li>\n<\/ol>\n<p>[<strong>REPRODUCCI\u00d3N PERMITIDA<\/strong> \u2013 Este es un ejercicio privado de devoci\u00f3n &#8220;<em>ad experimentum<\/em>&#8221; en proceso de aprobaci\u00f3n oficial. Puede divulgarse en las redes sociales, blogs, emisoras de radio, y otros medios siempre que al mismo tiempo se haga la presente advertencia.]<\/p>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1140,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[291,1265],"tags":[],"class_list":["post-115123","post","type-post","status-publish","format-standard","hentry","category-audio","category-rosario-de-las-semanas"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/115123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1140"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=115123"}],"version-history":[{"count":1,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/115123\/revisions"}],"predecessor-version":[{"id":115130,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/115123\/revisions\/115130"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=115123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=115123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=115123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}