{"id":104709,"date":"2023-11-25T12:41:35","date_gmt":"2023-11-25T17:41:35","guid":{"rendered":"https:\/\/fraynelson.com\/blog\/?p=104709"},"modified":"2023-11-22T16:45:46","modified_gmt":"2023-11-22T21:45:46","slug":"la-gracia-2023-11-27-nos-llenamos-de-cosas-porque-estamos-vacios-de-amores","status":"publish","type":"post","link":"https:\/\/fraynelson.com\/blog\/2023\/11\/25\/la-gracia-2023-11-27-nos-llenamos-de-cosas-porque-estamos-vacios-de-amores\/","title":{"rendered":"LA GRACIA 2023\/11\/27 Nos llenamos de cosas porque estamos vac\u00edos de amores"},"content":{"rendered":"<p>Pon en primer lugar el amor a Jes\u00fas y su Evangelio y seguro que vas a descubrir que hay muchas cosas que te sobran. Nos llenamos de cosas porque estamos vac\u00edos de amores.<\/p>\n<p><iframe loading=\"lazy\" title=\"LA GRACIA 2023\/11\/27 Nos llenamos de cosas porque estamos vac\u00edos de amores\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/gIqDoKl1hRo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><div class=\"powerpress_player\" id=\"powerpress_player_3396\"><audio class=\"wp-audio-shortcode\" id=\"audio-104709-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/traffic.libsyn.com\/fraynelson\/20231127.mp3?_=1\" \/><a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/20231127.mp3\">http:\/\/traffic.libsyn.com\/fraynelson\/20231127.mp3<\/a><\/audio><\/div><p class=\"powerpress_links powerpress_links_mp3\" style=\"margin-bottom: 1px !important;\">Podcast: <a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/20231127.mp3\" class=\"powerpress_link_pinw\" target=\"_blank\" title=\"Play in new window\" onclick=\"return powerpress_pinw('https:\/\/fraynelson.com\/blog\/?powerpress_pinw=104709-podcast');\" rel=\"nofollow\">Play in new window<\/a> | <a href=\"http:\/\/traffic.libsyn.com\/fraynelson\/20231127.mp3\" class=\"powerpress_link_d\" title=\"Download\" rel=\"nofollow\" download=\"20231127.mp3\">Download<\/a><\/p><p class=\"powerpress_links powerpress_subscribe_links\">Subscribe: <a href=\"https:\/\/fraynelson.com\/blog\/feed\/podcast\/\" class=\"powerpress_link_subscribe powerpress_link_subscribe_rss\" target=\"_blank\" title=\"Subscribe via RSS\" rel=\"nofollow\">RSS<\/a><\/p>[<strong>REPRODUCCI\u00d3N PERMITIDA<\/strong> <em>en redes sociales, blogs, emisoras de radio, y otros medios<\/em>. <span style=\"color: #993300;\">Tu donaci\u00f3n hace fuerte la evangelizaci\u00f3n cat\u00f3lica. <a style=\"color: #993300;\" href=\"https:\/\/paypal.me\/fraynelsonmedina?locale.x=es_XC\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a1Dona ahora<\/a>!<\/span>]<\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Pon en primer lugar el amor a Jes\u00fas y su Evangelio y seguro que vas a descubrir que hay muchas cosas que te sobran. Nos llenamos de cosas porque estamos vac\u00edos de amores.<\/p>\n","protected":false},"author":1140,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311,291,307,841,356,836,302],"tags":[],"class_list":["post-104709","post","type-post","status-publish","format-standard","hentry","category-amor_de_cristo","category-audio","category-homilias","category-micro-homilias","category-sanacion","category-sanar-voluntad-herida","category-video"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/104709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/users\/1140"}],"replies":[{"embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/comments?post=104709"}],"version-history":[{"count":1,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/104709\/revisions"}],"predecessor-version":[{"id":104710,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/posts\/104709\/revisions\/104710"}],"wp:attachment":[{"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/media?parent=104709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/categories?post=104709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fraynelson.com\/blog\/wp-json\/wp\/v2\/tags?post=104709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}